{"id":98809,"date":"2023-03-09T15:14:11","date_gmt":"2023-03-09T18:14:11","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=98809"},"modified":"2023-03-09T15:14:11","modified_gmt":"2023-03-09T18:14:11","slug":"emotivo-homenaje-a-valeria-leoncino-victima-de-femicidio-ella-fue-a-pedir-ayuda-y-no-se-la-dieron","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2023\/03\/09\/emotivo-homenaje-a-valeria-leoncino-victima-de-femicidio-ella-fue-a-pedir-ayuda-y-no-se-la-dieron\/","title":{"rendered":"Emotivo homenaje a Valeria Leoncino, v\u00edctima de femicidio: \u201cElla fue a pedir ayuda y no se la dieron\u201d"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>En conmemoraci\u00f3n al D\u00eda Internacional de la Mujer, se llev\u00f3 a cabo una marcha en Concordia que reuni\u00f3 a cientos de personas, en la Plaza \u201c25 de Mayo\u201d<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s de las reivindicaciones hist\u00f3ricas y actuales en materia de igualdad de g\u00e9nero, en esta oportunidad la movilizaci\u00f3n tuvo un enfoque especial por el reciente asesinato de Valeria Leoncino, una joven concordiense v\u00edctima de femicidio.<\/p>\n<p>Familiares y amigas de Valeria se movilizaron tras el acto que comenz\u00f3 en la plaza principal de la ciudad y continu\u00f3 con una vuelta a ese lugar. Los presentes aprovecharon la oportunidad para reclamar por justicia, frente a la Jefatura de Polic\u00eda.<\/p>\n<p>Adem\u00e1s de los allegados a la v\u00edctima, en la movilizaci\u00f3n se hicieron presentes representantes de diferentes agrupaciones populares y organizaciones. Este 8 de marzo fue una jornada de lucha y de reclamo, pero tambi\u00e9n de solidaridad y de uni\u00f3n en torno de una causa que conmocion\u00f3 a la ciudad en esta semana.<\/p>\n<p>Algunas de las amigas de la joven dejaron su valioso testimonio, tal como los recogi\u00f3 \u201cAhora\u201d. A continuaci\u00f3n, algunas frases pronunciadas por quienes conoc\u00edan a la v\u00edctima de tres disparos a quemarropa efectuados por Carlos Passarella, que poco despu\u00e9s se quit\u00f3 la vida.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&#8220;Ella fue a pedir ayudar pero&#8230;&#8221;<\/strong><\/p>\n<p>&#8220;Vale era una persona alegre&#8221;, cont\u00f3 una amiga, entre l\u00e1grimas, al punto que no pudo continuar hablando. &#8220;Por ah\u00ed mucho no queremos hablar porque ya est\u00e1 todo dicho. Pero nosotras podemos asegurar que ella fue a pedir ayuda y no se la dieron&#8221;, agreg\u00f3 otra.<\/p>\n<p>Otra de las mujeres presentes en la movilizaci\u00f3n: \u201cEstamos conmocionadas por lo que leyeron las chicas. Te llega al coraz\u00f3n, es triste y horrible que est\u00e9 pasando esto a un d\u00eda del d\u00eda de la mujer y que siga pasando. Te deja sin palabras\u201d, afirm\u00f3.<\/p>\n<p>\u201cEs la primera vez ya que, por una cosa y otra, no he podido\u201d, revel\u00f3 luego y concluy\u00f3: \u201ces muy lindo, es hermoso que se junten tantas chicas a luchar por nuestros derechos, por todos los que por ah\u00ed no nos permiten participar. La igualdad. Es muy lindo este espacio\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En conmemoraci\u00f3n al D\u00eda Internacional de la Mujer, se llev\u00f3 a cabo una marcha en Concordia que reuni\u00f3 a cientos de personas, en la Plaza \u201c25 de Mayo\u201d &nbsp; &nbsp; &nbsp; Adem\u00e1s de las reivindicaciones hist\u00f3ricas y actuales en materia de igualdad de g\u00e9nero, en esta oportunidad la movilizaci\u00f3n tuvo un enfoque especial por el reciente asesinato de Valeria Leoncino, una joven concordiense v\u00edctima de femicidio. Familiares y amigas de Valeria se movilizaron tras el acto que comenz\u00f3 en la plaza principal de la ciudad y continu\u00f3 con una vuelta&#8230;<\/p>\n","protected":false},"author":3,"featured_media":98810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/98809"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=98809"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/98809\/revisions"}],"predecessor-version":[{"id":98811,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/98809\/revisions\/98811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/98810"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=98809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=98809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=98809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}