{"id":7919,"date":"2017-03-06T10:20:28","date_gmt":"2017-03-06T13:20:28","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7919"},"modified":"2017-03-06T10:20:28","modified_gmt":"2017-03-06T13:20:28","slug":"prorrogan-plazo-para-adquirir-uno-de-los-bonos-del-blanqueo","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/03\/06\/prorrogan-plazo-para-adquirir-uno-de-los-bonos-del-blanqueo\/","title":{"rendered":"Prorrogan plazo para adquirir uno de los bonos del blanqueo"},"content":{"rendered":"<p><em><strong>A trav\u00e9s de un Decreto de Necesidad y Urgencia (DNU), el Gobierno nacional extendi\u00f3 hasta fin de mes el plazo para adquirir el bono a 7 a\u00f1os para quienes se adhieran al R\u00e9gimen de Sinceramiento Fiscal, a trav\u00e9s del cual pueden evitar el pago de la multa<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La medida, publicado en el Bolet\u00edn Oficial, modifica el apartado 2 del inciso a) del art\u00edculo 42 de la Ley N\u00b0 27.260 de &#8220;Reparaci\u00f3n Hist\u00f3rica para Jubilados y Pensionados&#8221;, llevando el l\u00edmite para la compra del BONAR 1 por ciento 2023 hasta el 31 de marzo de 2017, cuando la fecha original era el 31 de diciembre de 2016.<\/p>\n<p>&#8220;Que con posterioridad al 31 de diciembre de 2016 numerosos contribuyentes han formulado solicitudes para acceder al R\u00e9gimen de Sinceramiento Fiscal a trav\u00e9s de la adquisici\u00f3n de \u00b4Bonos de la Rep\u00fablica Argentina en d\u00f3lares estadounidenses 1% vencimiento 2023 (BONAR 1% 2023)\u00b4, lo que no ha sido posible a tenor de la fecha de vencimiento prevista&#8221;, afirma la norma entre sus considerandos.<\/p>\n<p>Adem\u00e1s, siempre seg\u00fan el decreto, &#8220;la emisi\u00f3n del BONAR 1% 2023, oportunamente realizada, no ha sido totalmente colocada&#8221;.<\/p>\n<p>La Ley de Reparaci\u00f3n Hist\u00f3rica, que incluye el R\u00e9gimen de Sinceramiento Fiscal, permit\u00eda la adquisici\u00f3n de t\u00edtulos p\u00fablicos o participaci\u00f3n en Fondos Comunes de Inversi\u00f3n por la tercera parte del capital exteriorizado, lo que except\u00faa del impuesto no s\u00f3lo al monto involucrado en la compra de t\u00edtulos, sino al total de los fondos declarados.<\/p>\n<p>Las opciones que otorg\u00f3 el Gobierno fue un bono en d\u00f3lares a 3 a\u00f1os (BONAR 0% 2019&#8243;) y el mencionado BONAR 1% 2023, el cual es intransferible y no negociable durante los primeros cuatro a\u00f1os, aunque luego podr\u00e1 liquidarse en el mercado secundario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de un Decreto de Necesidad y Urgencia (DNU), el Gobierno nacional extendi\u00f3 hasta fin de mes el plazo para adquirir el bono a 7 a\u00f1os para quienes se adhieran al R\u00e9gimen de Sinceramiento Fiscal, a trav\u00e9s del cual pueden evitar el pago de la multa &nbsp; &nbsp; &nbsp; La medida, publicado en el Bolet\u00edn Oficial, modifica el apartado 2 del inciso a) del art\u00edculo 42 de la Ley N\u00b0 27.260 de &#8220;Reparaci\u00f3n Hist\u00f3rica para Jubilados y Pensionados&#8221;, llevando el l\u00edmite para la compra del BONAR 1 por ciento&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7920,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7919"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7919"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7919\/revisions"}],"predecessor-version":[{"id":7921,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7919\/revisions\/7921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7920"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}