{"id":7895,"date":"2017-03-02T11:17:42","date_gmt":"2017-03-02T14:17:42","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7895"},"modified":"2017-03-02T11:17:42","modified_gmt":"2017-03-02T14:17:42","slug":"trump-solo-logra-20-de-los-20-000-millones-necesarios-para-construir-el-muro-con-mexico","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/03\/02\/trump-solo-logra-20-de-los-20-000-millones-necesarios-para-construir-el-muro-con-mexico\/","title":{"rendered":"Trump solo logra 20 de los 20.000 millones necesarios para construir el muro con M\u00e9xico"},"content":{"rendered":"<p><em><strong>Un documento obtenido por la agencia Reuters revela la ausencia de fondos para cumplir la promesa estrella del presidente republicano<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La Administraci\u00f3n de Donald Trump carece de los fondos suficientes para financiar la construcci\u00f3n del muro en la frontera con M\u00e9xico. Seg\u00fan un documento oficial obtenido por la agencia Reuters, el gobierno estadounidense solo ha identificado la suma de 20 millones de d\u00f3lares entre el presupuesto que puede destinar a cumplir la mayor promesa electoral de Trump. Las \u00faltimas estimaciones oficiales aseguran que el coste de la construcci\u00f3n ascender\u00e1 a 20.000 millones de d\u00f3lares.<\/p>\n<p>Un mes despu\u00e9s de llegar al Gobierno, el gabinete de Trump solo ha identificado, de acuerdo con el documento enviado a varios legisladores y al que ha tenido acceso Reuters, dos partidas de 5 y 15 millones de d\u00f3lares respectivamente. Ambas corresponden a contratos previos para la seguridad en la frontera que no llegaron a ser asignados. El total de 20 millones es una cifra que est\u00e1 muy lejos incluso de las primeras estimaciones del republicano, que asegur\u00f3 que el coste no superar\u00eda los 8.000 millones de d\u00f3lares.<\/p>\n<p>El mandatario asegur\u00f3 en un primero momento que ser\u00eda el gobierno de Pe\u00f1a Nieto quien costeara el precio del muro, para despu\u00e9s moderar su postura y afirmar que los estadounidenses pagar\u00edan primero y M\u00e9xico lo reembolsar\u00eda despu\u00e9s. La Casa Blanca ha ido rebajando las exigencias hasta afirmar ahora que la edificaci\u00f3n del muro ser\u00eda financiada con \u201cfondos ya existentes\u201d del Departamento de Seguridad Nacional.<\/p>\n<p>\u201cVamos a comenzar a construir un gran muro muy, muy pronto\u201d, declar\u00f3 el presidente republicano este mi\u00e9rcoles durante su intervenci\u00f3n ante el Congreso. La frase no es nueva, pero el obst\u00e1culo s\u00ed. La falta de fondos puede convertirse ahora en el mayor desaf\u00edo para que el magnate, que ha hecho de esta obra el eje de su estrategia para luchar contra la inmigraci\u00f3n ilegal, demuestre que puede cumplir lo que prometi\u00f3 a su electorado.<\/p>\n<p>La ausencia de recursos en las arcas de EE UU supone que Trump necesitar\u00e1 convencer al Congreso de que apruebe, en la negociaci\u00f3n del pr\u00f3ximo presupuesto federal, una dotaci\u00f3n para el muro que es cinco veces superior al presupuesto de seguridad en la frontera, cerca de 4.000 millones de d\u00f3lares. Seg\u00fan las \u00faltimas estimaciones del Departamento de Seguridad Nacional, la construcci\u00f3n prometida por Trump ascender\u00e1 a 21.600 millones de d\u00f3lares, y varios legisladores de su propio partido ya han declarado que no respaldar\u00e1n el presupuesto salvo que est\u00e9 acompa\u00f1ado de recortes al gasto p\u00fablico.<\/p>\n<p>Esto obliga a Trump a elegir entre elevar el d\u00e9ficit, en contra de lo que han defendido hasta ahora los republicanos, aprobar una subida de impuestos para financiar una obra que seg\u00fan el presidente iba a ser costeada por M\u00e9xico, o recortar programas p\u00fablicos que prometi\u00f3 no tocar durante la campa\u00f1a y que adem\u00e1s pueden reforzar los argumentos contra \u00e9l por parte de los dem\u00f3cratas y de buena parte de la sociedad estadounidense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un documento obtenido por la agencia Reuters revela la ausencia de fondos para cumplir la promesa estrella del presidente republicano &nbsp; &nbsp; &nbsp; La Administraci\u00f3n de Donald Trump carece de los fondos suficientes para financiar la construcci\u00f3n del muro en la frontera con M\u00e9xico. Seg\u00fan un documento oficial obtenido por la agencia Reuters, el gobierno estadounidense solo ha identificado la suma de 20 millones de d\u00f3lares entre el presupuesto que puede destinar a cumplir la mayor promesa electoral de Trump. Las \u00faltimas estimaciones oficiales aseguran que el coste de la&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7895"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7895"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7895\/revisions"}],"predecessor-version":[{"id":7897,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7895\/revisions\/7897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7896"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}