{"id":7835,"date":"2017-03-02T10:42:40","date_gmt":"2017-03-02T13:42:40","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7835"},"modified":"2017-03-02T10:42:40","modified_gmt":"2017-03-02T13:42:40","slug":"la-oposicion-califico-de-mentiroso-y-cinico-el-discurso-de-macri-en-el-congreso","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/03\/02\/la-oposicion-califico-de-mentiroso-y-cinico-el-discurso-de-macri-en-el-congreso\/","title":{"rendered":"La oposici\u00f3n calific\u00f3 de &#8220;mentiroso&#8221; y &#8220;c\u00ednico&#8221; el discurso de Macri en el Congreso"},"content":{"rendered":"<p><em><strong>Legisladores de distintos espacios pol\u00edticos coincidieron en que los conceptos expresados por el Presidente estuvieron &#8220;alejados de la realidad&#8221;<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El discurso del presidente Mauricio Macri ante la Asamblea Legislativa para inaugurar el 135\u00ba per\u00edodo de sesiones ordinarias en el Congreso fue duramente criticado por diputados y senadores de todo el arco opositor.<\/p>\n<p>Desde que estuvo cargado de &#8220;slogans de campa\u00f1a&#8221; y lleno de &#8220;voluntarismo&#8221; hasta tildarlo de &#8220;mentiroso&#8221;, &#8220;c\u00ednico&#8221; y &#8220;alejado de la realidad&#8221;, el discurso de Macri gener\u00f3 indignaci\u00f3n entre los legisladores consultados.<\/p>\n<p>&#8220;En esta apertura no tiene que hablar de ninguna herencia, tiene que venir y decirnos a los argentinos lo que va a hacer a partir de ahora para mejorar la calidad de vida y generar un desarrollo sustentable de la sociedad&#8221;, advirti\u00f3 H\u00e9ctor Daer (Unidos por Una Nueva Argentina) y acus\u00f3 de que Macri &#8220;plantea slongans y cifras sin ning\u00fan dato emp\u00edrico que se pueda contrarrestar&#8221;.<\/p>\n<p>Para Oscar Romero (Justicialista), el discurso estuvo &#8220;cargado de voluntarismo&#8221;. El presidente del bloque, que tambi\u00e9n integra Diego Bossio, dijo que &#8220;la Argentina no se resuelve con creer o no creer&#8221;. Y se mostr\u00f3 preocupado al salir de la Asamblea Legislativa: &#8220;Me da la impresi\u00f3n de que el Presidente todav\u00eda no tom\u00f3 la dimensi\u00f3n de la problem\u00e1tica que atraviesa gran parte de la sociedad&#8221;.<\/p>\n<p>El representante de Frente de Izquierda Socialista, Juan Carlos Giordano, expres\u00f3: &#8220;Fue un discurso horrible, al servicio de los bancos, de las multinacionales, de las mineras y de los fondos buitre, que si estaban escuchando lo habr\u00e1n aplaudido&#8221;.<\/p>\n<p>M\u00e1s duro en su cr\u00edtica fue Edgardo Depetri (Frente para la Victoria) quien tild\u00f3 a Macri de &#8220;c\u00ednico&#8221; e ironiz\u00f3: &#8220;Parece que es el presidente de Suiza. Del mismo espacio, Jos\u00e9 Luis Gioja consider\u00f3 que hubo algunos temas pendientes. &#8220;No mencion\u00f3 los esc\u00e1ndalos del Correo, ni el que envuelve al Jefe de la Inteligencia, Gustavo Arribas, tampoco habl\u00f3 de los Panam\u00e1 Papers, no se refiri\u00f3 a los conflictos de intereses que tienen como protagonistas a miembros de su familia como a su padre o a su primo Calcaterra&#8221;, dijo.<\/p>\n<p>El diputado Carlos Heller (Partido Solidario) opin\u00f3 que \u201cgenera mucha preocupaci\u00f3n un discurso que ya no tiene casi puntos de contacto con la realidad&#8221;. Al t\u00e9rmino de la Asamblea Legislativa, dijo: \u201cEl discurso de Macri est\u00e1 en perfecta oposici\u00f3n a lo que producen sus pol\u00edticas ya que dice que su desaf\u00edo m\u00e1s grande es &#8216;sacar a los argentinos de la pobreza&#8217;, mientras el modelo econ\u00f3mico que implementa va contra esa premisa y genera cada vez m\u00e1s pobreza&#8221;.<\/p>\n<p>En algunos pasajes del discurso, Macri carg\u00f3 contra &#8220;la pesada herencia&#8221; y que venimos de una &#8220;d\u00e9cada de despilfarro y corrupci\u00f3n&#8221;. No hay que olvidar que una de las promesas de campa\u00f1a de Cambiemos era &#8220;unir a los argentinos&#8221; y poco ayuda con frases as\u00ed. &#8220;Profundiza esa grieta que se supone que existe entre distintos sectores pol\u00edticos y, en realidad, la sociedad es v\u00edctima de otra grieta que es la de la desigualdad, de los que son v\u00edctimas del aumento de la pobreza y de los que quedan del lado de los desocupados&#8221;, marc\u00f3 la diputada Lucila de Ponti (Peronismo para la Victoria).<\/p>\n<p>Por \u00faltimo, la legisladora se\u00f1al\u00f3 que &#8220;fue un discurso mentiroso en t\u00e9rminos de que se afirmaron una serie de pol\u00edticas y la reivindicaci\u00f3n de algunos ejes de gobierno que no est\u00e1n representados en las medidas que se llevan a cabo&#8221;. Y agreg\u00f3: &#8220;Lo not\u00e9 agresivo con algunas manifestaciones, como en la que nombr\u00f3 a Baradel, que fue inapropiado para un discurso presidencial&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Legisladores de distintos espacios pol\u00edticos coincidieron en que los conceptos expresados por el Presidente estuvieron &#8220;alejados de la realidad&#8221; &nbsp; &nbsp; El discurso del presidente Mauricio Macri ante la Asamblea Legislativa para inaugurar el 135\u00ba per\u00edodo de sesiones ordinarias en el Congreso fue duramente criticado por diputados y senadores de todo el arco opositor. Desde que estuvo cargado de &#8220;slogans de campa\u00f1a&#8221; y lleno de &#8220;voluntarismo&#8221; hasta tildarlo de &#8220;mentiroso&#8221;, &#8220;c\u00ednico&#8221; y &#8220;alejado de la realidad&#8221;, el discurso de Macri gener\u00f3 indignaci\u00f3n entre los legisladores consultados. &#8220;En esta apertura no&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7836,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7835"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7835"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7835\/revisions"}],"predecessor-version":[{"id":7837,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7835\/revisions\/7837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7836"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}