{"id":7815,"date":"2017-01-24T13:09:46","date_gmt":"2017-01-24T16:09:46","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7815"},"modified":"2017-01-24T13:09:46","modified_gmt":"2017-01-24T16:09:46","slug":"bordet-ratifico-la-convocatoria-a-paritarias-en-febrero","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/24\/bordet-ratifico-la-convocatoria-a-paritarias-en-febrero\/","title":{"rendered":"Bordet ratific\u00f3 la convocatoria a paritarias en febrero"},"content":{"rendered":"<p><em><strong>El mandatario precis\u00f3 que la invitaci\u00f3n a los gremios docentes y de trabajadores estatales ser\u00e1 en los primeros d\u00edas del mes de febrero. Dio cuenta de trabajos en las escuelas del Estado<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El Gobernador de la provincia Gustavo Bordet confirm\u00f3 que el estado entrerriano llamar\u00e1 a los gremios para negociar salarios en el marco de paritarias. No anticip\u00f3 la fecha pero asever\u00f3 que la convocatoria \u201cser\u00e1 en el mes de febrero\u201d. Fue en el marco de la firma de un contrato de obra para iniciar la construcci\u00f3n del nuevo edificio de la Escuela N\u00ba100 Puerto Nuevo de Paran\u00e1.<\/p>\n<p>&nbsp;<\/p>\n<p>En el Sal\u00f3n de los Gobernadores de Casa de Gobierno, este martes se firm\u00f3 un contrato de obra para comenzar la construcci\u00f3n del nuevo edificio de la Escuela N\u00ba100 Puerto Nuevo de Paran\u00e1. El acto fue presidido por el gobernador de la provincia Gustavo Bordet que destac\u00f3 la importancia de \u201cfortalecer\u201d a las escuelas de educaci\u00f3n t\u00e9cnica. \u201cPara que haya generaci\u00f3n de industrias es fundamental tener una educaci\u00f3n que acompa\u00f1e\u201d, se\u00f1al\u00f3 al remarcar que esta escuela de Paran\u00e1 es \u201cemblem\u00e1tica para la ciudad y la regi\u00f3n\u201d, expres\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>La obra tiene un presupuesto que supera los 95 millones, con un financiamiento gestionado ante el Instituto Nacional de Educaci\u00f3n Tecnol\u00f3gica (INET). El edificio contar\u00e1 con espacios \u00e1ulicos y talleres especialmente dise\u00f1ados en funci\u00f3n de la formaci\u00f3n, as\u00ed como un canal de experiencias hidrodin\u00e1micas. El inicio de obra est\u00e1 previsto para febrero de 2017.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Paritarias<\/strong><\/p>\n<p>Por otra parte, hizo referencia a las negociaciones gremiales y asever\u00f3 que se convocar\u00e1 a \u201ctodos los gremios\u201d, tanto a docentes como a \u201crepresentantes de la administraci\u00f3n central, para poder tener un espacio de discusi\u00f3n salarial\u201d, se\u00f1al\u00f3 en di\u00e1logo con el m\u00f3vil de LT14.<\/p>\n<p>&nbsp;<\/p>\n<p>El primer mandatario entrerriano no anticip\u00f3 la fecha de inicio de paritarias pero adelant\u00f3 que la convocatoria \u201cser\u00e1 en los primeros d\u00edas del mes de febrero\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo remarc\u00f3 que se realizan trabajos y reparaciones en edificios escolares de la provincia para llegar al inicio de clases \u201cen buenas condiciones\u201d y con \u201ctotal normalidad\u201d, asever\u00f3 Bordet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mandatario precis\u00f3 que la invitaci\u00f3n a los gremios docentes y de trabajadores estatales ser\u00e1 en los primeros d\u00edas del mes de febrero. Dio cuenta de trabajos en las escuelas del Estado &nbsp; &nbsp; &nbsp; &nbsp; El Gobernador de la provincia Gustavo Bordet confirm\u00f3 que el estado entrerriano llamar\u00e1 a los gremios para negociar salarios en el marco de paritarias. No anticip\u00f3 la fecha pero asever\u00f3 que la convocatoria \u201cser\u00e1 en el mes de febrero\u201d. Fue en el marco de la firma de un contrato de obra para iniciar la&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7815"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7815"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7815\/revisions"}],"predecessor-version":[{"id":7817,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7815\/revisions\/7817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7816"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}