{"id":7791,"date":"2017-01-24T12:51:54","date_gmt":"2017-01-24T15:51:54","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7791"},"modified":"2017-01-24T12:51:54","modified_gmt":"2017-01-24T15:51:54","slug":"el-gobierno-justifico-dnu-por-reforma-de-regimen-de-art-busca-cortar-con-la-industria-del-juicio-laboral","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/24\/el-gobierno-justifico-dnu-por-reforma-de-regimen-de-art-busca-cortar-con-la-industria-del-juicio-laboral\/","title":{"rendered":"El Gobierno justific\u00f3 DNU por reforma de r\u00e9gimen de ART: &#8220;Busca cortar con la industria del juicio laboral&#8221;"},"content":{"rendered":"<p><em><strong>El Gobierno sali\u00f3 a defender el Decreto de Necesidad y Urgencia (DNU), mediante el cual modific\u00f3 la ley de Aseguradoras de Riesgos del Trabajo (ART) y estableci\u00f3 una nueva figura en ese r\u00e9gimen, denominado &#8220;Comisiones M\u00e9dicas Jurisdiccionales&#8221;<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El encargado de hacerlo fue el jefe de Gabinete, Marcos Pe\u00f1a, quien sostuvo que el decreto del Poder Ejecutivo Nacional &#8220;busca cortar de forma urgente con la industria del juicio laboral, que funciona con una l\u00f3gica mafiosa&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Pe\u00f1a dijo que el contenido del decreto est\u00e1 en l\u00ednea &#8220;con el proyecto de modificaci\u00f3n que sali\u00f3 con alto nivel de consenso&#8221; en el Senado de la Naci\u00f3n a fines del a\u00f1o pasado.<\/p>\n<p>&nbsp;<\/p>\n<p>En la misma l\u00ednea se expres\u00f3 el ministro de Trabajo, Jorge Triaca, se\u00f1al\u00f3 que la reforma que impuls\u00f3 el Gobierno apunta a &#8220;cuidar los derechos de los trabajadores y a darle m\u00e1s certeza&#8221; al sistema.<\/p>\n<p>&nbsp;<\/p>\n<p>El titular de la cartera laboral explic\u00f3 que el decreto de necesidad y urgencia, que fue publicado ayer en el Bolet\u00edn Oficial, fija &#8220;un criterio uniforme para cada uno de los accidentes y de los siniestros que ocurran&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Sin embargo, la oposici\u00f3n no est\u00e1 de acuerdo con la decisi\u00f3n del Ejecutivo. el senador del Frente para la Victoria, Juan Manuel Abal Medina, afirm\u00f3 en di\u00e1logo con Radio 10 que &#8220;es incre\u00edble y absolutamente inconstitucional&#8221; la utilizaci\u00f3n del DNU para modificar el r\u00e9gimen de ART para un proyecto que ya tiene media sanci\u00f3n en el Congreso.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;No hace falta un planteo en la Justicia porque el pr\u00f3ximo jueves vamos a reunir a la bicameral. Es obvio y evidente que este DNU no tiene las condiciones necesarias para ser aprobado&#8221;, dispar\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>En tanto, el diputado Marcos Cleri consider\u00f3 que &#8220;no hay necesidad y urgencia en este caso de las (modificaciones al r\u00e9gimen de) ART&#8221;, a la vez que evalu\u00f3 que desde el oficialismo &#8220;lo pod\u00edan haber llevado al Congreso en (sesiones) extraordinarias&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte, la Confederaci\u00f3n General del Trabajo (CGT), tambi\u00e9n cuestion\u00f3 el decreto. As\u00ed lo hizo saber H\u00e9ctor Daer, uno de los secretarios generales que conduce el triunvirato de la central obrera, quien se\u00f1al\u00f3 que la medida publicada en el Bolet\u00edn Oficial &#8220;no es el mecanismo adecuando&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>En declaraciones a Radio 10, Daer dijo que &#8220;lo ideal era que el proyecto siguiera el curso parlamentario&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno sali\u00f3 a defender el Decreto de Necesidad y Urgencia (DNU), mediante el cual modific\u00f3 la ley de Aseguradoras de Riesgos del Trabajo (ART) y estableci\u00f3 una nueva figura en ese r\u00e9gimen, denominado &#8220;Comisiones M\u00e9dicas Jurisdiccionales&#8221; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; El encargado de hacerlo fue el jefe de Gabinete, Marcos Pe\u00f1a, quien sostuvo que el decreto del Poder Ejecutivo Nacional &#8220;busca cortar de forma urgente con la industria del juicio laboral, que funciona con una l\u00f3gica mafiosa&#8221;. &nbsp; Pe\u00f1a dijo que el contenido del decreto est\u00e1 en&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7791"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7791"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7791\/revisions"}],"predecessor-version":[{"id":7793,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7791\/revisions\/7793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7792"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}