{"id":7786,"date":"2017-01-24T12:47:07","date_gmt":"2017-01-24T15:47:07","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7786"},"modified":"2017-01-24T12:47:07","modified_gmt":"2017-01-24T15:47:07","slug":"fuertes-criticas-de-la-oposicion-por-el-traslado-de-feriados","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/24\/fuertes-criticas-de-la-oposicion-por-el-traslado-de-feriados\/","title":{"rendered":"Fuertes cr\u00edticas de la oposici\u00f3n por el traslado de feriados"},"content":{"rendered":"<p><em><strong>La decisi\u00f3n de Macri de modificar algunos feriados nacionales desat\u00f3 una fuerte pol\u00e9mica con dirigentes de la oposici\u00f3n y referentes de los Derechos Humanos<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Las principales cr\u00edticas apuntaron a la decisi\u00f3n de hacer movibles fechas clave como el 24 de marzo y el 2 de abril, que conmemoran el \u00faltimo Golpe de Estado y el inicio de la guerra de Malvinas. Sin embargo, el traslado por el D\u00eda de la Bandera tambi\u00e9n desat\u00f3 fuertes cuestionamientos.<\/p>\n<p>&nbsp;<\/p>\n<p>Vale recordar que hace m\u00e1s de diez a\u00f1os el 24 de marzo se instaur\u00f3 como feriado nacional inamovible por el D\u00eda de la Memoria, por la Verdad y la Justicia. Al respecto, la integrante de Madres de Plaza de Mayo L\u00ednea Fundadora, Nora Corti\u00f1as, record\u00f3 que antes de que &#8220;el 24 es 24, no lo cambian de la historia&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>La referente por los derechos humanos destac\u00f3 que &#8220;en la memoria est\u00e1 el 24 de marzo como el d\u00eda que se instaur\u00f3 la gran dictadura c\u00edvico, militar, religiosa y econ\u00f3mica en nuestro pa\u00eds&#8221;. En declaraciones radiales Corti\u00f1as consider\u00f3 que &#8220;querer borrar un d\u00eda de la historia, del calendario, es imposible&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte, el ex ministro Agust\u00edn Rossi asegur\u00f3 que &#8220;no sorprende&#8221; la decisi\u00f3n, ya que cuando Macri era diputado nacional &#8220;estuvo ausente el d\u00eda que se vot\u00f3 el feriado del 24 de marzo&#8221; y denunci\u00f3 que el Gobierno &#8220;pretende terminar con la masividad de los actos&#8221; de organismos de derechos humanos.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;A partir de ahora el 24 de marzo y el 2 de abril son movibles y esta modificaci\u00f3n no es inocente, es un claro retroceso&#8221;, consider\u00f3 Rossi y agreg\u00f3 que, con el cambio en el D\u00eda de los Ca\u00eddos en la Guerra de Malvinas, el Gobierno &#8220;da un paso m\u00e1s en el proceso de desmalvinizaci\u00f3n&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>El diputado del Parlasur tambi\u00e9n expres\u00f3 su &#8220;malestar&#8221; por el DNU que tambi\u00e9n alcanza al 20 de junio, D\u00eda de la Bandera, &#8220;una fecha muy importante para todos los rosarinos y santafesinos&#8221; y rechaz\u00f3 su nuevo car\u00e1cter de trasladable.<\/p>\n<p>&nbsp;<\/p>\n<p>Quien tambi\u00e9n cuestion\u00f3 la modificaci\u00f3n de este feriado fue la intendenta de Rosario, la socialista M\u00f3nica Fein, quien sostuvo que &#8220;el D\u00eda de la Bandera debe ser inamovible&#8221; y calific\u00f3 la decisi\u00f3n como &#8220;un grave error&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Considero lamentable la decisi\u00f3n de volver a trasladar el feriado nacional del 20 de Junio. El D\u00eda de la Bandera debe ser inamovible&#8221;, escribi\u00f3 Fein en su cuenta de Twitter. La intendenta del Frente Progresista agreg\u00f3 que &#8220;a trav\u00e9s de un DNU se retrocede en un reclamo hist\u00f3rico de todos los santafesinos y en una ley&#8221; que ella misma impuls\u00f3 siendo diputada nacional.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Durante mucho tiempo la Legislatura planteaba que trasladarlo permit\u00eda tener fines de semanas m\u00e1s tur\u00edsticos, pero nosotros siempre discutimos eso, porque no hay que confundir fechas hist\u00f3ricas con d\u00edas tur\u00edsticos&#8221;, argument\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La decisi\u00f3n de Macri de modificar algunos feriados nacionales desat\u00f3 una fuerte pol\u00e9mica con dirigentes de la oposici\u00f3n y referentes de los Derechos Humanos &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Las principales cr\u00edticas apuntaron a la decisi\u00f3n de hacer movibles fechas clave como el 24 de marzo y el 2 de abril, que conmemoran el \u00faltimo Golpe de Estado y el inicio de la guerra de Malvinas. Sin embargo, el traslado por el D\u00eda de la Bandera tambi\u00e9n desat\u00f3 fuertes cuestionamientos. &nbsp; Vale recordar que hace m\u00e1s de diez a\u00f1os el&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7636,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7786"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7786"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7786\/revisions"}],"predecessor-version":[{"id":7787,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7786\/revisions\/7787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7636"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}