{"id":7671,"date":"2017-01-20T11:02:29","date_gmt":"2017-01-20T14:02:29","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7671"},"modified":"2017-01-20T11:02:29","modified_gmt":"2017-01-20T14:02:29","slug":"prorrogan-por-un-ano-la-emergencia-de-seguridad","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/20\/prorrogan-por-un-ano-la-emergencia-de-seguridad\/","title":{"rendered":"Prorrogan por un a\u00f1o la Emergencia de Seguridad"},"content":{"rendered":"<p><em><strong>El Gobierno decidi\u00f3 extender por un a\u00f1o la declaraci\u00f3n de la Emergencia de Seguridad P\u00fablica debido a &#8220;los esfuerzos realizados y los \u00e9xitos obtenidos&#8221; en el combate del delito<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La medida, dispuesta originalmente mediante el decreto 228 del 21 de enero de 2016, fue extendida a trav\u00e9s del decreto 50\/2017, que se publica hoy en el Bolet\u00edn Oficial con las firmas del presidente Mauricio Macri y la ministra de Seguridad de la Naci\u00f3n, Patricia Bullrich.<\/p>\n<p>&nbsp;<\/p>\n<p>La pr\u00f3rroga es &#8220;por el t\u00e9rmino de 365 d\u00edas corridos a partir de la fecha de su vencimiento, la que podr\u00e1 ser prorrogada fundadamente&#8221;, se\u00f1ala la nueva disposici\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Al argumentar la decisi\u00f3n, el Poder Ejecutivo Nacional remarc\u00f3 que &#8220;a la fecha se han tomado diferentes medidas destinadas a dar cumplimiento al decreto de Emergencia de Seguridad P\u00fablica&#8221; y, como parte de ellas, destac\u00f3 &#8220;la puesta en marcha del Operativo Fronteras&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo, remarc\u00f3 que tambi\u00e9n &#8220;se han establecido las bases para elevar los niveles de formaci\u00f3n de las fuerzas federales&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>En el decreto publicado hoy tambi\u00e9n se record\u00f3 que la Emergencia de Seguridad P\u00fablica estuvo motivada &#8220;por la falta de respuesta satisfactoria a las demandas sociales de mayor seguridad por parte del Estado, tales como el impacto de la inseguridad social sobre los sectores vulnerables del pueblo argentino, los delitos de trata de personas, el narcotr\u00e1fico y sus delitos asociados&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno decidi\u00f3 extender por un a\u00f1o la declaraci\u00f3n de la Emergencia de Seguridad P\u00fablica debido a &#8220;los esfuerzos realizados y los \u00e9xitos obtenidos&#8221; en el combate del delito &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; La medida, dispuesta originalmente mediante el decreto 228 del 21 de enero de 2016, fue extendida a trav\u00e9s del decreto 50\/2017, que se publica hoy en el Bolet\u00edn Oficial con las firmas del presidente Mauricio Macri y la ministra de Seguridad de la Naci\u00f3n, Patricia Bullrich. &nbsp; La pr\u00f3rroga es &#8220;por el t\u00e9rmino de 365&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7671"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7671"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7671\/revisions"}],"predecessor-version":[{"id":7673,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7671\/revisions\/7673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7672"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}