{"id":7644,"date":"2017-01-19T12:04:01","date_gmt":"2017-01-19T15:04:01","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7644"},"modified":"2017-01-19T12:04:01","modified_gmt":"2017-01-19T15:04:01","slug":"hablo-gonzalez-fraga-ya-no-sirve-estimular-el-consumo-genera-inflacion","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/19\/hablo-gonzalez-fraga-ya-no-sirve-estimular-el-consumo-genera-inflacion\/","title":{"rendered":"Habl\u00f3 Gonz\u00e1lez Fraga: &#8220;Ya no sirve estimular el consumo; genera inflaci\u00f3n&#8221;"},"content":{"rendered":"<p><em><strong>El nuevo presidente del Banco Naci\u00f3n se mostr\u00f3 preocupado por la &#8220;falta de reacci\u00f3n&#8221; de la inversi\u00f3n. &#8220;Yo no soy un cirujano enamorado de un bistur\u00ed&#8221;<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El flamante presidente del Banco Naci\u00f3n, Javier Gonz\u00e1lez Fraga, dio sus primeros lineamientos en su nuevo cargo. All\u00ed, reiter\u00f3 su pr\u00e9dica contra el consumo, al que consider\u00f3 inflacionario, y se mostr\u00f3 preocupado por la falta de reacci\u00f3n de la inversi\u00f3n en este a\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n<p>En declaraciones a radio Mitre, el pol\u00e9mico economista de origen radical remarc\u00f3 que quiere &#8220;un pa\u00eds de propietarios&#8221;, luego de que criticara el consumo de electrodom\u00e9sticos, celulares y viajes al exterior por parte de la clase media.<\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo, dijo que no es &#8220;un cirujano que se enamorado de un bistur\u00ed&#8221; aunque desestim\u00f3 que el gobierno est\u00e9 realizando pol\u00edticas gradualistas. Incre\u00edblemente, se mostr\u00f3 entusiasmado porque &#8220;el Gobierno est\u00e1 atacando los problemas y cuidando a los que menos tienen&#8221;, en lugar de &#8220;terminar de enriquecer a los que m\u00e1s tienen&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo presidente del Banco Naci\u00f3n se mostr\u00f3 preocupado por la &#8220;falta de reacci\u00f3n&#8221; de la inversi\u00f3n. &#8220;Yo no soy un cirujano enamorado de un bistur\u00ed&#8221; &nbsp; &nbsp; &nbsp; El flamante presidente del Banco Naci\u00f3n, Javier Gonz\u00e1lez Fraga, dio sus primeros lineamientos en su nuevo cargo. All\u00ed, reiter\u00f3 su pr\u00e9dica contra el consumo, al que consider\u00f3 inflacionario, y se mostr\u00f3 preocupado por la falta de reacci\u00f3n de la inversi\u00f3n en este a\u00f1o. &nbsp; En declaraciones a radio Mitre, el pol\u00e9mico economista de origen radical remarc\u00f3 que quiere &#8220;un pa\u00eds de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7644"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7644"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7644\/revisions"}],"predecessor-version":[{"id":7646,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7644\/revisions\/7646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7645"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}