{"id":7617,"date":"2017-01-19T11:36:40","date_gmt":"2017-01-19T14:36:40","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7617"},"modified":"2017-01-19T11:36:40","modified_gmt":"2017-01-19T14:36:40","slug":"motoclicistas-en-harley-la-curiosa-seguridad-privada-de-trump-para-su-asuncion","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/19\/motoclicistas-en-harley-la-curiosa-seguridad-privada-de-trump-para-su-asuncion\/","title":{"rendered":"Motoclicistas en Harley, la curiosa &#8220;seguridad privada&#8221; de Trump para su asunci\u00f3n"},"content":{"rendered":"<p><em><strong>El presidente electo de EE.UU., Donald Trump, augur\u00f3 que su toma de posesi\u00f3n del viernes ser\u00e1 masiva y se refiri\u00f3 al grupo de motociclistas que est\u00e1 viajando a Washington para protegerlo de las protestas, a los que describi\u00f3 como &#8220;una seguridad a\u00f1adida&#8221;<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Montan en esas Harley, generalmente son Harley, hechas aqu\u00ed en Estados Unidos. Hoy los vimos en unas tomas desde unos helic\u00f3pteros sobrevolando una carretera en alg\u00fan lugar del pa\u00eds. Hay miles de estos tipos viniendo a la ciudad. Son grandes personas y creo que logr\u00e9 el 100% de sus votos&#8221;, asegur\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>El presidente electo hizo una visita fugaz a Washington tras m\u00e1s de un mes de ausencia y a tan solo tres d\u00edas de su toma de posesi\u00f3n para asistir a una cena con 500 diplom\u00e1ticos, pol\u00edticos y empresarios.<\/p>\n<p>&nbsp;<\/p>\n<p>En su discurso, Trump sac\u00f3 a relucir su caracter\u00edstico estilo y elogi\u00f3 a su elegido para comandar la diplomacia estadounidense, el petrolero Rex Tillerson, con el que ironiz\u00f3 sobre su nuevo trabajo.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Me parece que es m\u00e1s duro de lo que \u00e9l cre\u00eda. Ha dejado su vida de ensue\u00f1o. Iba a un pa\u00eds, se llevaba el petr\u00f3leo, iba a otro pa\u00eds. Es duro tratar con estos pol\u00edticos, \u00bfcierto? \u00c9l va a ser incre\u00edble&#8221;, dijo Trump, al declararse &#8220;orgulloso&#8221; de todo su gabinete.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente electo de EE.UU., Donald Trump, augur\u00f3 que su toma de posesi\u00f3n del viernes ser\u00e1 masiva y se refiri\u00f3 al grupo de motociclistas que est\u00e1 viajando a Washington para protegerlo de las protestas, a los que describi\u00f3 como &#8220;una seguridad a\u00f1adida&#8221; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8220;Montan en esas Harley, generalmente son Harley, hechas aqu\u00ed en Estados Unidos. Hoy los vimos en unas tomas desde unos helic\u00f3pteros sobrevolando una carretera en alg\u00fan lugar del pa\u00eds. Hay miles de estos tipos viniendo a la ciudad. Son grandes personas y&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7617"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7617"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7617\/revisions"}],"predecessor-version":[{"id":7619,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7617\/revisions\/7619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7618"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}