{"id":7553,"date":"2017-01-17T11:06:00","date_gmt":"2017-01-17T14:06:00","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7553"},"modified":"2017-01-17T11:06:00","modified_gmt":"2017-01-17T14:06:00","slug":"carnaval-de-gualeguaychu-entrerrianos-podran-adquirir-entradas-con-descuentos","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/17\/carnaval-de-gualeguaychu-entrerrianos-podran-adquirir-entradas-con-descuentos\/","title":{"rendered":"Carnaval de Gualeguaych\u00fa: entrerrianos podr\u00e1n adquirir entradas con descuentos"},"content":{"rendered":"<p><em><strong>El Carnaval del Pa\u00eds vuelve a ofrecer entradas accesibles para el p\u00fablico local. Mientra sigue vigente la promoci\u00f3n para residentes, se anunci\u00f3 un importante beneficio que comprende al resto de la provincia<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La Comisi\u00f3n del Carnaval del Pa\u00eds decidi\u00f3 que los residentes de Gualeguaych\u00fa y del Departamento vuelvan a tener el beneficio de adquirir entradas promocionales a 50 pesos, para la segunda jornada de la m\u00e1xima fiesta a cielo abierto del verano en Argentina que se realizar\u00e1 \u00e9ste s\u00e1bado 21 de enero.<\/p>\n<p>&nbsp;<\/p>\n<p>La medida se tom\u00f3 durante la reuni\u00f3n de este lunes por la noche, en reconocimiento al acompa\u00f1amiento masivo del p\u00fablico local y del interior del Departamento que asisti\u00f3 al Cors\u00f3dromo el s\u00e1bado, marcando un record de concurrencia desde que se implement\u00f3 el sistema de entrada promocional para los residentes de Gualeguaych\u00fa.<\/p>\n<p>&nbsp;<\/p>\n<p>En ese sentido, los n\u00fameros oficiales indican que en la primera noche de carnaval m\u00e1s del 50% del p\u00fablico presente en el Cors\u00f3dromo (de las m\u00e1s de 27 mil personas que asistieron) acredit\u00f3 domicilio en alguna localidad del departamento Gualeguaych\u00fa.<\/p>\n<p>&nbsp;<\/p>\n<p>Las entradas al precio promocional de 50 pesos podr\u00e1n adquirirse \u00fanicamente en las boleter\u00edas del Cors\u00f3dromo hasta el viernes 20, bajo la misma modalidad que la primera noche: se vender\u00e1 una por persona y presentando el DNI como requisito excluyente.<\/p>\n<p>&nbsp;<\/p>\n<p>En tanto, se inform\u00f3 que quienes compren la entrada a 50 pesos podr\u00e1n adquirir las ubicaciones en sillas, pullman o sectores vip a partir de la tercera fila.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Promoci\u00f3n para toda la provincia<\/strong><\/p>\n<p>Por otra parte, y en una medida in\u00e9dita para el Carnaval, la Comisi\u00f3n organizadora decidi\u00f3 extender para toda la provincia el beneficio de adquirir entradas al 50% del valor oficial, para la segunda noche que se realizar\u00e1 el s\u00e1bado 21 de enero.<\/p>\n<p>&nbsp;<\/p>\n<p>Al beneficio acceder\u00e1n las personas que acrediten residencia en cualquiera de las localidades de la provincia de Entre R\u00edos (excepto Gualeguaych\u00fa y el departamento), quienes podr\u00e1n adquirir la entrada \u00fanicamente en las boleter\u00edas del Cors\u00f3dromo, hasta el viernes 20, presentando DNI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Carnaval del Pa\u00eds vuelve a ofrecer entradas accesibles para el p\u00fablico local. Mientra sigue vigente la promoci\u00f3n para residentes, se anunci\u00f3 un importante beneficio que comprende al resto de la provincia &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; La Comisi\u00f3n del Carnaval del Pa\u00eds decidi\u00f3 que los residentes de Gualeguaych\u00fa y del Departamento vuelvan a tener el beneficio de adquirir entradas promocionales a 50 pesos, para la segunda jornada de la m\u00e1xima fiesta a cielo abierto del verano en Argentina que se realizar\u00e1 \u00e9ste s\u00e1bado 21 de enero. &nbsp; La medida&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7554,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7553"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7553"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7553\/revisions"}],"predecessor-version":[{"id":7555,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7553\/revisions\/7555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7554"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}