{"id":7529,"date":"2017-01-17T10:59:37","date_gmt":"2017-01-17T13:59:37","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7529"},"modified":"2017-01-17T10:59:37","modified_gmt":"2017-01-17T13:59:37","slug":"mas-aumentos-en-celulares-el-plan-prepago-subira-hasta-15","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/17\/mas-aumentos-en-celulares-el-plan-prepago-subira-hasta-15\/","title":{"rendered":"M\u00e1s aumentos en celulares: el plan prepago subir\u00e1 hasta 15%"},"content":{"rendered":"<p><em><strong>El Gobierno acord\u00f3 la continuidad del Plan Prepago Nacional (PPN) con una suba de hasta 15% para los servicios de datos y radios llamadas a partir del 15 de marzo<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>De esta manera, el secretario de Comercio, Miguel Braun, y el presidente del Ente Nacional de Comunicaciones, Miguel \u00c1ngel de Godoy, anunciaron la continuidad del plan con las cuatro empresas proveedoras de servicios de telefon\u00eda celular: Claro, Movistar, Nextel y Personal.<\/p>\n<p>&nbsp;<\/p>\n<p>Si bien la renovaci\u00f3n del plan llega con un aumento promedio de 9,5% para los servicios de voz y mendajaer\u00eda, los servicios de datos de -internet m\u00f3vil- y las radio llamadas costar\u00e1n un 15% m\u00e1s.<\/p>\n<p>&nbsp;<\/p>\n<p>Vale recordar que el Plan Prepago Nacional es un plan de telefon\u00eda m\u00f3vil que incluye servicios de voz, mensajes e Internet con precios entre un 40 % y un 67 % promedio m\u00e1s bajo que los planes prepagos que ofrecen las distintas empresas del sector.<\/p>\n<p>&nbsp;<\/p>\n<p>El objetivo del Plan Prepago Nacional fue implementado en agosto de 2014 y ya cuenta con m\u00e1s de 718.000 usuarios en todo el pa\u00eds. Desde enero de 2016, la cantidad de usuarios de este plan se ha incrementado un 20%.<\/p>\n<p>&nbsp;<\/p>\n<p>Para acceder al plan de telefon\u00eda m\u00f3vil con los precios m\u00e1s bajos del mercado, los usuarios deben solicitar el Plan Prepago Nacional en oficinas comerciales o en los centros de atenci\u00f3n telef\u00f3nica de cada uno de los operadores de telefon\u00eda m\u00f3vil, sin costo alguno de adhesi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Los precios de los abonos de los celulares forman parte de una serie de aumentos que est\u00e1n pautados para el primer cuatrimestre del a\u00f1o. Desde este mes, los clientes de Movistar pagan un 10,5% m\u00e1s en su abono. En tanto, Personal tiene planteado subir el servicio a partir del pr\u00f3ximo mes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno acord\u00f3 la continuidad del Plan Prepago Nacional (PPN) con una suba de hasta 15% para los servicios de datos y radios llamadas a partir del 15 de marzo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; De esta manera, el secretario de Comercio, Miguel Braun, y el presidente del Ente Nacional de Comunicaciones, Miguel \u00c1ngel de Godoy, anunciaron la continuidad del plan con las cuatro empresas proveedoras de servicios de telefon\u00eda celular: Claro, Movistar, Nextel y Personal. &nbsp; Si bien la renovaci\u00f3n del plan llega con un aumento promedio de 9,5%&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7529"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7529"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7529\/revisions"}],"predecessor-version":[{"id":7531,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7529\/revisions\/7531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7530"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}