{"id":7434,"date":"2017-01-16T11:32:16","date_gmt":"2017-01-16T14:32:16","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7434"},"modified":"2017-01-16T11:32:16","modified_gmt":"2017-01-16T14:32:16","slug":"el-gobierno-busca-restringir-el-ingreso-de-inmigrantes-con-antecedentes","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/16\/el-gobierno-busca-restringir-el-ingreso-de-inmigrantes-con-antecedentes\/","title":{"rendered":"El Gobierno busca restringir el ingreso de inmigrantes con antecedentes"},"content":{"rendered":"<p><em><strong>El Gobierno busca restringir el ingreso de inmigrantes que tengan antecedentes penales, a trav\u00e9s de un decreto o ley<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Estamos recibiendo inmigrantes que vienen con una carga personal que hay que revisar. Cuando est\u00e1s recibiendo gente que ya de por s\u00ed tiene un registro de delincuencia, es una situaci\u00f3n particular, no es un migrante: es eventualmente alguien que est\u00e1 escapando de la ley, o alguien con estado de inmigraci\u00f3n que al mismo tiempo delinque&#8221;, manifest\u00f3 la canciller Susana Malcorra.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;No podemos -agreg\u00f3 la ministra- volvernos un pa\u00eds cerrado, pero al mismo tiempo tenemos que ser un pa\u00eds responsable de que acogemos a aquellos que vienen a la Argentina a ser parte de un proyecto con buena voluntad&#8221;. &#8220;\u00bfQu\u00e9 se entiende por &#8216;buena voluntad&#8217;? Esas cuestiones son las que la ley o la revisi\u00f3n de la ley va a tratar de ajustar&#8221;, desliz\u00f3 Malcorra al diario Clar\u00edn.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan trascendi\u00f3, en el Gobierno no dudan que hay que tomar medidas. Aunque s\u00ed subyacen diferencias respecto a c\u00f3mo implementarlas. Hay quienes creen que se debe hacer a trav\u00e9s un proyecto de ley o un decreto, otros que entienden que alcanza con aplicar con firmeza la legislaci\u00f3n vigente.<\/p>\n<p>&nbsp;<\/p>\n<p>Y citan el inciso C del art\u00edculo 29 de la ley 25.871, de Migraciones, que fija como impedimento para el ingreso y permanencia a aquel extranjero que haya sido &#8220;condenado&#8221; o tenga &#8220;antecedentes por tr\u00e1fico de armas, de personas, de estupefacientes o por lavado de dinero o inversiones en actividades il\u00edcitas&#8221; o por &#8220;un delito que merezca para la legislaci\u00f3n argentina pena privativa de la libertad de tres (3) a\u00f1os o m\u00e1s&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Este \u00faltimo punto, creen en el Gobierno, es la llave para &#8220;depurar&#8221; el ingreso. El asunto es que, en muchos casos, no se cuenta con la informaci\u00f3n de los pa\u00edses de origen. &#8220;Con algunos, como Colombia, ya empez\u00f3 a funcionar el intercambio de informaci\u00f3n migratoria, pero nos falta mucho&#8221;, confiesan desde Migraciones. La intenci\u00f3n es avanzar en m\u00e1s acuerdos de cooperaci\u00f3n para reunir esos datos. Y, al mismo tiempo, acelerar los plazos de expulsi\u00f3n de los inmigrantes que delinquen: &#8220;Hoy con la industria de la apelaci\u00f3n hay casos que tardan hasta ocho a\u00f1os&#8221;, se\u00f1alan. El porcentaje de extranjeros que delinquen es bajo: seg\u00fan datos oficiales, apenas el 6 por ciento de la poblaci\u00f3n carcelaria son extranjeros.<\/p>\n<p>&nbsp;<\/p>\n<p>Si bien descart\u00f3 que una posici\u00f3n m\u00e1s r\u00edgida pueda impactar en las relaciones exteriores (&#8220;La Argentina tiene una de las leyes de inmigraci\u00f3n m\u00e1s permisivas del mundo&#8221;), Malcorra advirti\u00f3: &#8220;Al mundo le fue muy mal siendo xen\u00f3fobo. No llegamos a ning\u00fan buen puerto con eso. No es que cualquiera puede entrar, pero tampoco podemos estigmatizar y cerrarnos, porque nuestro pa\u00eds es lo que es por los inmigrantes que vinieron&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno busca restringir el ingreso de inmigrantes que tengan antecedentes penales, a trav\u00e9s de un decreto o ley &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8220;Estamos recibiendo inmigrantes que vienen con una carga personal que hay que revisar. Cuando est\u00e1s recibiendo gente que ya de por s\u00ed tiene un registro de delincuencia, es una situaci\u00f3n particular, no es un migrante: es eventualmente alguien que est\u00e1 escapando de la ley, o alguien con estado de inmigraci\u00f3n que al mismo tiempo delinque&#8221;, manifest\u00f3 la canciller Susana Malcorra. &nbsp; &#8220;No podemos -agreg\u00f3 la&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7435,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7434"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7434"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7434\/revisions"}],"predecessor-version":[{"id":7436,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7434\/revisions\/7436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7435"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}