{"id":7419,"date":"2017-01-16T11:27:54","date_gmt":"2017-01-16T14:27:54","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7419"},"modified":"2017-01-16T11:27:54","modified_gmt":"2017-01-16T14:27:54","slug":"ya-son-mas-de-500-los-evacuados-por-las-lluvias-en-el-sur-de-santa-fe","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/16\/ya-son-mas-de-500-los-evacuados-por-las-lluvias-en-el-sur-de-santa-fe\/","title":{"rendered":"Ya son m\u00e1s de 500 los evacuados por las lluvias en el sur de Santa Fe"},"content":{"rendered":"<p><em><strong>Alrededor de quinientos personas fueron evacuadas de distintas localidades del sur de Santa Fe como consecuencia de las inundaciones provocadas el \u00faltimo fin de semana por las intensas lluvias ca\u00eddas, por lo que gobernador Miguel Lifschitz asegur\u00f3 que se pusieron &#8220;todos los recursos del Estado a disposici\u00f3n para enfrentar la emergencia&#8221;<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Una de las localidades m\u00e1s afectadas la ca\u00edda de m\u00e1s 300 mil\u00edmetros de lluvia desde la madrugada del domingo fue Arroyo Seco, que vivi\u00f3 una inundaci\u00f3n hist\u00f3rica y adem\u00e1s, no s\u00f3lo tiene el problema del agua que cae sobre el casco urbano y los alrededores, sino tambi\u00e9n de la que escurre del lado de Fighiera, cada vez que \u00e9sta se inunda.<\/p>\n<p>&nbsp;<\/p>\n<p>En taonto, otras localidades como Peblo Esther, Chab\u00e1s, Firmat, Murphy, Elortondo, Wheelwright, Labordeboy, Miguel Torres, entre otras se vieron seriamente afectadas por el fen\u00f3meno clim\u00e1tico, donde las precipitaciones fueron diferentes pero todas sufrieron el avance de las aguas.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Estamos poniendo todos los recursos del Estado a disposici\u00f3n para enfrentar la emergencia&#8221;, afirm\u00f3 el gobernador Lifschitz, quien analiz\u00f3 la situaci\u00f3n de la emergencia h\u00eddrica que afecta a buena parte del territorio provincial junto a los ministros de Seguridad, Maximiliano Pullaro; de Infraestructura y Transporte, Jos\u00e9 Garibay; y de Producci\u00f3n, Luis Contigiani; y el secretario de Protecci\u00f3n Civil, Marcos Escajadillo.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante la reuni\u00f3n el mandatario provincial recibi\u00f3 informes de la situaci\u00f3n y mantuvo contacto con intendentes y presidentes comunales de localidades afectadas, seg\u00fan consign\u00f3 el matutino rosarino La Capital.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Estamos monitoreando la situaci\u00f3n minuto a minuto, con equipos recorriendo el territorio y trabajando denodadamente. Personalmente he tomado contacto con intendentes, presidentes comunales y senadores para interiorizarme de la situaci\u00f3n de cada una de las localidades afectadas y coordinar la llegada de toda la ayuda necesaria para paliar la situaci\u00f3n&#8221;, evalu\u00f3 Lifschitz.<\/p>\n<p>&nbsp;<\/p>\n<p>El mandatario provincial afirm\u00f3 que la que se vive &#8220;es una situaci\u00f3n in\u00e9dita&#8221; y sostuvo que se est\u00e1 &#8220;enfrentando con todos los recursos que tenemos a disposici\u00f3n&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Estamos trabajando en los centros de evacuados y tambi\u00e9n asistiendo con bombas para poder sacar el agua de las calles. Hay rutas cortadas por lo que tambi\u00e9n desplegamos operativos para ordenar el tr\u00e1nsito por las rutas santafesinas teniendo en cuenta que es un fin de semana de recambio tur\u00edstico&#8221;, se\u00f1al\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>En este contexto, el panorama no es alentador, ya que la lluvia no da tregua y el pron\u00f3stico del Servicio Meteorol\u00f3gico Nacional advirti\u00f3 que reci\u00e9n el martes mejorar\u00e1 el tiempo.<\/p>\n<p>&nbsp;<\/p>\n<p>En tanto, las rutas de la regi\u00f3n sur de la provincia de Santa Fe se encontraban cortadas debido a los desbordes de r\u00edos y a las intensas lluvias registradas en las \u00faltimas horas en la zona, informo Agencia Provincial de Seguridad Vial Santa Fe (APSV).<\/p>\n<p>&nbsp;<\/p>\n<p>La autopista Rosario-Buenos Aires, comenz\u00f3 a ser habilitada al tr\u00e1nsito a partir de las 7, con tr\u00e1nsito asistido hacia Rosario tras permanecer totalmente cortada en ambos sentidos a la altura de Arroyo Seco, pero con la posibilidad que se produzcan nuevas interrupciones.<\/p>\n<p>&nbsp;<\/p>\n<p>En otros sectores de la autopista, en el kil\u00f3metro 231, a la altura San Nicolas, tambi\u00e9n se encontraba totalmente interrumpida, y se desviaba por un camino paralelo con importantes demoras e inconvenientes para los conductores.<\/p>\n<p>&nbsp;<\/p>\n<p>Para evitar demoras, la APSV recomendaba a quienes se trasladen en veh\u00edculos desde Buenos Aires a Rosario, tomar por el complejo ferrovial Z\u00e1rate-Brazo Largo, y seguir por la ruta nacional 12 hasta la ruta provincial 11, en Entre R\u00edos, para cruzar finalmente por el puente Rosario Victoria, y el mismo trayecto inverso para quienes tengan como destino la ciudad de Buenos Aires.<\/p>\n<p>&nbsp;<\/p>\n<p>Otras rutas, tanto nacionales como provinciales, ten\u00edan un panorama similar, por lo que las autoridades viales solicitaban a quienes se movilicen por la zona, consultar el estado de los itinerarios para evitar mayores inconvenientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alrededor de quinientos personas fueron evacuadas de distintas localidades del sur de Santa Fe como consecuencia de las inundaciones provocadas el \u00faltimo fin de semana por las intensas lluvias ca\u00eddas, por lo que gobernador Miguel Lifschitz asegur\u00f3 que se pusieron &#8220;todos los recursos del Estado a disposici\u00f3n para enfrentar la emergencia&#8221; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Una de las localidades m\u00e1s afectadas la ca\u00edda de m\u00e1s 300 mil\u00edmetros de lluvia desde la madrugada del domingo fue Arroyo Seco, que vivi\u00f3 una inundaci\u00f3n hist\u00f3rica y adem\u00e1s, no s\u00f3lo tiene&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7420,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7419"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7419"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7419\/revisions"}],"predecessor-version":[{"id":7421,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7419\/revisions\/7421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7420"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}