{"id":7416,"date":"2017-01-16T11:26:54","date_gmt":"2017-01-16T14:26:54","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7416"},"modified":"2017-01-16T11:26:54","modified_gmt":"2017-01-16T14:26:54","slug":"ministros-inician-gira-en-busca-de-inversion-y-financiamiento","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/16\/ministros-inician-gira-en-busca-de-inversion-y-financiamiento\/","title":{"rendered":"Ministros inician gira en busca de inversi\u00f3n y financiamiento"},"content":{"rendered":"<p><em><strong>Los ministros de Hacienda, Nicol\u00e1s Dujovne; de Producci\u00f3n, Francisco Cabrera, y de Relaciones Exteriores, Susana Malcorra, parten con destino a Davos, Suiza, donde participar\u00e1n de una nueva edici\u00f3n del Foro de Econom\u00eda Global<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Durante su estad\u00eda, se prev\u00e9 que los funcionarios intentar\u00e1n aliviar tensiones comerciales con China y regenerar la agenda con los socios estrat\u00e9gicos a nivel global.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n concurrir\u00e1 al tradicional encuentro el titular de la cartera de Educaci\u00f3n, Esteban Bullrich, y presidente del Banco Central, Federico Sturzenegger, quien estar\u00e1 acompa\u00f1ado por el vicepresidente segundo del organismo, Demian Reidel.<\/p>\n<p>&nbsp;<\/p>\n<p>Este a\u00f1o no viajar\u00e1 el presidente Mauricio Macri, quien s\u00ed asisti\u00f3 a pocas semanas de asumir a la anterior edici\u00f3n del foro de negocios y mantuvo reuniones con empresarios e inversores de alto nivel.<\/p>\n<p>&nbsp;<\/p>\n<p>Los ministros tuvieron el viernes pasado una reuni\u00f3n de trabajo en el Palacio de Hacienda, junto a funcionarios de diferentes carteras, para analizar la agenda de trabajo y preparar las reuniones que se llevar\u00e1n a cabo en el marco de ese encuentro.<\/p>\n<p>&nbsp;<\/p>\n<p>Del Foro Econ\u00f3mico, que se realizar\u00e1 a partir del 17 de enero participar\u00e1n m\u00e1s de cien pa\u00edses, 1.200 CEOs de multinacionales y m\u00e1s de 50 jefes de Estado.<\/p>\n<p>&nbsp;<\/p>\n<p>Mientras una parte del equipo econ\u00f3mico asistir\u00e1 al foro, otra parte se encontrar\u00e1 en diferentes puntos de Estados Unidos y Europa para estrechar lazos con posibles inversores y presentar la emisi\u00f3n de deuda que la Argentina realizar\u00e1 el jueves.<\/p>\n<p>&nbsp;<\/p>\n<p>En este marco, el titular de la cartera de Finanzas, Luis Caputo, viajar\u00e1 este lunes a Londres, de cara a la nueva colocaci\u00f3n de deuda que se concretar\u00e1 el jueves por un monto de u$s 5.000 millones en el mercado exterior, y otro bono en pesos equivalente a u$s 2.000 millones en el mercado local.<\/p>\n<p>&nbsp;<\/p>\n<p>Tras pasar por Londres, Caputo viajar\u00e1 a Boston, en los Estados Unidos, para seguir el martes en Los \u00c1ngeles y concluir el jueves en Nueva York.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Es una forma alternativa de financiamiento que nos permite salir al mercado la semana que viene con mayor tranquilidad a buscar nuevos fondos&#8221;, reconoci\u00f3 Caputo el jueves durante una conferencia de prensa, al dejar sentado que no habr\u00e1 apuro en completar los u$s 20.000 millones de nueva deuda que piensan tomar.<\/p>\n<p>&nbsp;<\/p>\n<p>Esta suerte de pr\u00e9stamo, denominado REPO, seg\u00fan su sigla en ingl\u00e9s, y en el que el Estado entreg\u00f3 t\u00edtulos Bonar 2024 como garant\u00eda, fue acordado con los bancos Santander, BBVA Franc\u00e9s, Citibank, Deutsche Bank, HSBC y el JP Morgan, las mismas entidades que el jueves pr\u00f3ximo tendr\u00e1n a su cargo la colocaci\u00f3n de la nueva deuda por hasta u$s 5.000 millones, en el mercado exterior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ministros de Hacienda, Nicol\u00e1s Dujovne; de Producci\u00f3n, Francisco Cabrera, y de Relaciones Exteriores, Susana Malcorra, parten con destino a Davos, Suiza, donde participar\u00e1n de una nueva edici\u00f3n del Foro de Econom\u00eda Global &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Durante su estad\u00eda, se prev\u00e9 que los funcionarios intentar\u00e1n aliviar tensiones comerciales con China y regenerar la agenda con los socios estrat\u00e9gicos a nivel global. &nbsp; Tambi\u00e9n concurrir\u00e1 al tradicional encuentro el titular de la cartera de Educaci\u00f3n, Esteban Bullrich, y presidente del Banco Central, Federico Sturzenegger, quien estar\u00e1 acompa\u00f1ado por&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7417,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7416"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7416"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7416\/revisions"}],"predecessor-version":[{"id":7418,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7416\/revisions\/7418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7417"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}