{"id":7391,"date":"2017-01-13T11:13:40","date_gmt":"2017-01-13T14:13:40","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7391"},"modified":"2017-01-13T11:13:40","modified_gmt":"2017-01-13T14:13:40","slug":"entre-rios-comenzara-este-lunes-a-inmunizar-contra-el-vph-en-varones-y-el-meningococo","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/13\/entre-rios-comenzara-este-lunes-a-inmunizar-contra-el-vph-en-varones-y-el-meningococo\/","title":{"rendered":"Entre R\u00edos comenzar\u00e1 este lunes a inmunizar contra el VPH en varones y el meningococo"},"content":{"rendered":"<p><em><strong>A partir del lunes entrar\u00e1 en vigencia el nuevo Calendario Nacional de Vacunaci\u00f3n, el cual incorporar\u00e1 dos nuevas vacunas para inmunizar contra la meningitis y el Virus del Papiloma Humano en varones. El Ministerio de Salud de Entre R\u00edos distribuy\u00f3 en esta primera etapa 7.000 dosis de Antimeningococcica y m\u00e1s de 24.000 de VPH en los 357 vacunatorios de la provincia<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El Calendario Nacional de Vacunaci\u00f3n es una herramienta para el control de enfermedades efectivo en todo el territorio argentino, y promueve el acceso gratuito y obligatorio a las dosis necesarias para inmunizar contra las diferentes enfermedades.<\/p>\n<p>&nbsp;<\/p>\n<p>En este 2017, se incorporar\u00e1n dos nuevas vacunas. Los padres que lleven a sus hijos a cualquiera de los 357 vacunatorios distribuidos en la provincia se encontrar\u00e1n con un calendario renovado. Cabe aclarar que, al igual que las dem\u00e1s vacunas incluidas en el Calendario Nacional, las nuevas incorporaciones no requieren orden m\u00e9dica, son de acceso gratuito y de car\u00e1cter obligatorio.<\/p>\n<p>&nbsp;<\/p>\n<p>A partir de este lunes, los beb\u00e9s de 3 meses de edad ser\u00e1n inmunizados con la vacuna Antimeningococcica, haciendo un refuerzo a los 5 meses, y otro entre los 15 y 18 meses de vida. En tanto, los ni\u00f1os varones de 11 a\u00f1os, de la cohorte 2006, se sumar\u00e1n a la vacunaci\u00f3n contra el Virus del Papiloma Humano, la cual ya se est\u00e1 aplicando en ni\u00f1as desde el 2011.<\/p>\n<p>&nbsp;<\/p>\n<p>De cara a la nueva implementaci\u00f3n, el ministro de Salud de Entre R\u00edos, Ariel de la Rosa, encabez\u00f3 una reuni\u00f3n de trabajo con el director de Epidemiolog\u00eda, Diego Garcilazo, y la responsable del Programa Ampliado de Inmunizaciones (PAI), Albana Gavini, para ultimar detalles de la puesta en marcha de esta nueva estrategia.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEs un gran avance poder contar con estas nuevas vacunas en el calendario de acceso gratuito y obligatorio, ya que representa la cobertura de dos enfermedades que afectan en gran medida a los menores \u2014destac\u00f3 el ministro de Salud\u2014. En la primera etapa distribuimos 7.000 dosis de la vacuna contra meningitis, y 24.320 para prevenir el VPH. En el transcurso del a\u00f1o continuaremos abasteciendo a todos los hospitales y centros de salud que posean los vacunatorios oficiales\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte, Albana Gavini explic\u00f3: \u201cLa vacuna Antimeningococcica sirve para proteger de un germen muy agresivo que es la bacteria Neisseria Meningitidis, a la que com\u00fanmente la denominamos meningococo. Es invasiva y provoca cuadros graves, los cuales requieren terapia, una atenci\u00f3n especializada y que la mayor\u00eda de las veces termina en muerte, es decir, es una bacteria letal\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s, la profesional hizo referencia a la vacuna que desde este a\u00f1o se incorpor\u00f3 para ni\u00f1os varones: \u201cEs una estrategia complementaria a la incorporada en el 2011 para las ni\u00f1as nacidas en el 2000. Esto ya est\u00e1 en vigencia, empezamos los primeros d\u00edas de enero y vamos a ir monitoreando esta incorporaci\u00f3n al Calendario\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Contra la meningitis <\/strong><\/p>\n<p>La vacuna contra el meningococo est\u00e1 indicada para los beb\u00e9s que cumplan los tres meses a partir de enero de 2017 con un esquema de tres dosis a los 3, 5 y entre los 15 y 18 meses de vida.<\/p>\n<p>&nbsp;<\/p>\n<p>El meningococo es una bacteria que provoca enfermedades graves como la meningitis (inflamaci\u00f3n de la membrana que cubre el cerebro) y sepsis (infecci\u00f3n generalizada), con consecuencias fatales o secuelas neurol\u00f3gicas irreversibles como p\u00e9rdida de audici\u00f3n y discapacidad neurol\u00f3gica. Los ni\u00f1os menores de 1 a\u00f1o constituyen el grupo m\u00e1s vulnerables.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEsta bacteria tiene la caracter\u00edstica de invadir las v\u00edas respiratorias de los adultos y de ah\u00ed contagia a los ni\u00f1os. Es bastante complejo, porque el adulto es asintom\u00e1tico pero lo transmite a los ni\u00f1os y all\u00ed se genera la enfermedad. La vacuna es Menveo Tetravalente, y protege contra las cepas A, C, W135 e Y, que son las m\u00e1s prevalentes en estos momentos y m\u00e1s meningitis por meningococo provocan en nuestro pa\u00eds\u201d, indic\u00f3 Gavini.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Estrategia complementaria <\/strong><\/p>\n<p>El VPH es una familia de virus que alcanza tanto a varones como a mujeres. Existen alrededor de 100 tipos, de los cuales 40 afectan a la zona genital y\/o anal, y se dividen en 2 grandes grupos. Por un lado, los VPH de bajo riesgo oncog\u00e9nico, que generalmente se asocian a las lesiones benignas, como las verrugas y las lesiones de bajo grado y, por otro, los de alto riesgo oncog\u00e9nico que pueden evolucionar a lesiones precancerosas y a c\u00e1ncer.<\/p>\n<p>&nbsp;<\/p>\n<p>La vacuna se incorpora de manera complementaria a la que ya est\u00e1 en vigencia para mujeres, con el objetivo de generar equidad y disminuir la morbimortalidad por el virus que no s\u00f3lo genera c\u00e1ncer de cuello de \u00fatero sino que tambi\u00e9n produce c\u00e1ncer de pene, de perineo, y de far\u00edngeo en los varones en un alto porcentaje. Esta herramienta de inmunizaci\u00f3n se aplica a ni\u00f1os varones de 11 a\u00f1os de la cohorte 2006, en dos dosis, la primera al d\u00eda 0 y la segunda a los 6 meses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir del lunes entrar\u00e1 en vigencia el nuevo Calendario Nacional de Vacunaci\u00f3n, el cual incorporar\u00e1 dos nuevas vacunas para inmunizar contra la meningitis y el Virus del Papiloma Humano en varones. El Ministerio de Salud de Entre R\u00edos distribuy\u00f3 en esta primera etapa 7.000 dosis de Antimeningococcica y m\u00e1s de 24.000 de VPH en los 357 vacunatorios de la provincia &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; El Calendario Nacional de Vacunaci\u00f3n es una herramienta para el control de enfermedades efectivo en todo el territorio argentino, y promueve el acceso&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7392,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7391"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7391"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7391\/revisions"}],"predecessor-version":[{"id":7393,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7391\/revisions\/7393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7392"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}