{"id":7379,"date":"2017-01-13T11:10:36","date_gmt":"2017-01-13T14:10:36","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=7379"},"modified":"2017-01-13T11:10:36","modified_gmt":"2017-01-13T14:10:36","slug":"fuerte-reclamo-de-la-iglesia-por-la-represion-contra-los-mapuches","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/01\/13\/fuerte-reclamo-de-la-iglesia-por-la-represion-contra-los-mapuches\/","title":{"rendered":"Fuerte reclamo de la Iglesia por la represi\u00f3n contra los mapuches"},"content":{"rendered":"<p><em><strong>El Equipo Nacional de Pastoral repudi\u00f3 el &#8220;accionar represivo&#8221; de fuerzas de seguridad sobre la comunidad de la zona cordillerana de Chubut<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El Equipo Nacional de Pastoral Aborigen (Endepa) de la Iglesia Cat\u00f3lica repudi\u00f3 el &#8220;accionar represivo&#8221; de fuerzas de seguridad sobre la comunidad mapuche &#8220;Lof en Resistencia Cushamen&#8221; de la zona cordillerana de Chubut y advirti\u00f3 que &#8220;el respeto por los derechos de los pueblos ind\u00edgenas no se lograr\u00e1 criminalizando sus reclamos&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;El respeto por los derechos de los pueblos ind\u00edgenas no se lograr\u00e1 criminalizando sus reclamos. Se deben encontrar v\u00edas pac\u00edficas para solucionar los conflictos&#8221;, indic\u00f3 el organismo pastoral.<\/p>\n<p>&nbsp;<\/p>\n<p>En un comunicado, el Endepa reclam\u00f3 adem\u00e1s al gobierno nacional y al chubutense &#8220;el respeto por los derechos de los pueblos ind\u00edgenas, consagrados por la Constituci\u00f3n Nacional y los tratados internacionales&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s critic\u00f3 que se priorice &#8220;el inter\u00e9s de extranjeros por sobre el de los pueblos ind\u00edgenas, preexistentes al Estado argentino&#8221; y lament\u00f3 &#8220;el sufrimiento generado a tantos miembros del pueblo mapuche&#8221; con quienes se solidarizaron.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Nos preguntamos por qu\u00e9 los gobiernos no emplean, aunque sea una parte de todo ese personal, dinero, energ\u00eda, en implementar debidamente un sistema de consulta previa a los pueblos ind\u00edgenas, el relevamiento territorial ordenado por la ley 26.160, en suma, en cumplir con las normas vigentes y respetar a los pueblos originarios&#8221;, se agreg\u00f3 en el texto difundido por la agencia Aica.<\/p>\n<p>&nbsp;<\/p>\n<p>Endepa exhort\u00f3 tambi\u00e9n a los responsables de elaborar y ejecutar las pol\u00edticas de Estado, a que &#8220;se desista de imponer a sangre y fuego un orden basado en la injusticia, el despojo y la negaci\u00f3n de los derechos de los pueblos ind\u00edgenas&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;No ser\u00e1 f\u00e1cil solucionar los m\u00faltiples reclamos que decenas de pueblos ind\u00edgenas realizan hace tantos a\u00f1os, pero es el \u00fanico camino que podr\u00e1 proporcionar el respeto de los derechos en juego. La violencia y la represi\u00f3n estatal por otro lado, solo pueden generar m\u00e1s injusticia y menos paz social&#8221;, concluy\u00f3 el mensaje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Equipo Nacional de Pastoral repudi\u00f3 el &#8220;accionar represivo&#8221; de fuerzas de seguridad sobre la comunidad de la zona cordillerana de Chubut &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; El Equipo Nacional de Pastoral Aborigen (Endepa) de la Iglesia Cat\u00f3lica repudi\u00f3 el &#8220;accionar represivo&#8221; de fuerzas de seguridad sobre la comunidad mapuche &#8220;Lof en Resistencia Cushamen&#8221; de la zona cordillerana de Chubut y advirti\u00f3 que &#8220;el respeto por los derechos de los pueblos ind\u00edgenas no se lograr\u00e1 criminalizando sus reclamos&#8221;. &nbsp; &#8220;El respeto por los derechos de los pueblos ind\u00edgenas no se&#8230;<\/p>\n","protected":false},"author":3,"featured_media":7380,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7379"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7379"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7379\/revisions"}],"predecessor-version":[{"id":7381,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/7379\/revisions\/7381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/7380"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}