{"id":34167,"date":"2018-10-04T10:39:31","date_gmt":"2018-10-04T13:39:31","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=34167"},"modified":"2018-11-06T19:35:40","modified_gmt":"2018-11-06T22:35:40","slug":"todo-lo-que-hay-saber-para-tomar-un-credito","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2018\/10\/04\/todo-lo-que-hay-saber-para-tomar-un-credito\/","title":{"rendered":"Todo lo que hay saber para tomar un cr\u00e9dito"},"content":{"rendered":"<p><em><strong>Como consecuencia del nuevo esquema de pol\u00edtica monetaria, las tasas de cr\u00e9dito al p\u00fablico ya superan el 100%<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Con la llegada de Guido Sandleris a la presidencia del Banco Central, se decidi\u00f3 implementar un nuevo esquema de pol\u00edtica monetaria. El objetivo es muy claro, generar un crecimiento nulo de la base monetaria para junio del a\u00f1o pr\u00f3ximo y as\u00ed reducir la inflaci\u00f3n. Cabe recordar que este es uno de los grandes desaf\u00edos que tiene el Gobierno para el 2019 teniendo en cuenta que este a\u00f1o cerrar\u00eda por arriba del 40%.\u00a0 Para cumplir con dicho prop\u00f3sito, una de las medidas tomadas fue fijar la tasa de las Leliq a siete d\u00edas como una variable end\u00f3gena de este nuevo plan. Por ejemplo, ayer, cerr\u00f3 en casi 70%.<\/p>\n<p>&nbsp;<\/p>\n<p>La cuesti\u00f3n es que este esquema que est\u00e1 implementando el BCRA estar\u00eda atentando contra la toma de cr\u00e9ditos por parte del sector privado. Sucede que las tasas que ofrecen las entidades financieras por un pr\u00e9stamo personal ya superan el 100% de costo financiero total. Incluso, en algunos casos alcanzan hasta el 130%.<\/p>\n<p>&nbsp;<\/p>\n<p>De acuerdo con \u00c1mbito Financiero, al tener la tasa en niveles tan altos, se producen dos problemas. Por un lado, es muy dif\u00edcil que el tomador de cr\u00e9dito decida salir a financiarse a un costo tan elevado. Por el otro, el prestatario se enfrenta a un problema que en la jerga econ\u00f3mica se conoce como \u201cselecci\u00f3n adversa\u201d. Esto es cuando una parte de una transacci\u00f3n no tiene la informaci\u00f3n necesaria para poder distinguir las caracter\u00edsticas negativas de su contraparte. Esta desventaja es aprovechada por la parte m\u00e1s informada, la que estar\u00e1 dispuesta a completar una transacci\u00f3n precisamente cuando es menos ventajoso para su contraparte menos informada. Ante esta situaci\u00f3n, el banco, en este momento la parte menos informada, suele mostrar una mayor reticencia a realizar la transacci\u00f3n o puede ocurrir que ofrezca una tasa m\u00e1s elevada para la misma, llevando a que el mercado funcione de manera eficiente. En este \u00faltimo caso, el tomador de cr\u00e9dito (el agente m\u00e1s seguro) suele optar por no tomar el cr\u00e9dito, ya que el costo de la operaci\u00f3n se encarece mucho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como consecuencia del nuevo esquema de pol\u00edtica monetaria, las tasas de cr\u00e9dito al p\u00fablico ya superan el 100% &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Con la llegada de Guido Sandleris a la presidencia del Banco Central, se decidi\u00f3 implementar un nuevo esquema de pol\u00edtica monetaria. El objetivo es muy claro, generar un crecimiento nulo de la base monetaria para junio del a\u00f1o pr\u00f3ximo y as\u00ed reducir la inflaci\u00f3n. Cabe recordar que este es uno de los grandes desaf\u00edos que tiene el Gobierno para el 2019 teniendo en cuenta que este a\u00f1o&#8230;<\/p>\n","protected":false},"author":3,"featured_media":34168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/34167"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=34167"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/34167\/revisions"}],"predecessor-version":[{"id":34169,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/34167\/revisions\/34169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/34168"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=34167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=34167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=34167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}