{"id":31136,"date":"2018-08-08T10:36:44","date_gmt":"2018-08-08T13:36:44","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=31136"},"modified":"2018-11-06T19:40:22","modified_gmt":"2018-11-06T22:40:22","slug":"los-medicamentos-aumentaron-hasta-90-en-tres-meses","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2018\/08\/08\/los-medicamentos-aumentaron-hasta-90-en-tres-meses\/","title":{"rendered":"Los medicamentos aumentaron hasta 90% en tres meses"},"content":{"rendered":"<p><em><strong>Con una devaluaci\u00f3n de m\u00e1s del 50% en lo que va del a\u00f1o, los medicamentos en la Argentina ya subieron hasta 91% en s\u00f3lo tres meses, analizando los valores vigentes hasta abril respecto de los actuales. Un informe realizado por Consumidores Libres, a cargo de H\u00e9ctor Polino, compara los precios en los medicamentos y los n\u00fameros son exorbitantes. En tanto en la comparaci\u00f3n con 2015, los aumentos superan el 400%<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Los datos surgen del manual farmac\u00e9utico sobre 10 medicamentos de distintos grupos terap\u00e9uticos, entre los que se encuentran las aspirinas y el Clonazepam, entre otros para diversos tratamientos de enfermedades como la diabetes o la tiroides. Entre los precios m\u00e1s sorprendentes entre febrero y julio de este a\u00f1o, se encuentran, por nombre comercial, la cafiaspirina, que pas\u00f3 de un valor de 11,35 pesos el blister a 21,75, es decir, que en tres meses sufri\u00f3 un aumento del 91%. En el mismo per\u00edodo, el zocor para el tratamiento de diabetes pas\u00f3 de 348,48 a 495,54 pesos, es decir que subi\u00f3 un 42%.<\/p>\n<p>&nbsp;<\/p>\n<p>En tanto, comparado con el 2015 la cafiaspirina, por blister pas\u00f3 de 4,30 a 21,75, es decir, que el aumento en 3 a\u00f1os fue de un 405%. En tanto, para el tratamiento de tiroides, se pas\u00f3 de valer 44,99 a 199,33 pesos, es decir, que en ese per\u00edodo el incremento fue de 342,96%.<\/p>\n<p>&nbsp;<\/p>\n<p>En di\u00e1logo con este medio, el titular de Consumidores Libres, H\u00e9ctor Polino, se\u00f1al\u00f3 que &#8220;las farmacias no son las formadoras de precios: el problema est\u00e1 en los laboratorios y la falla es que la Secretar\u00eda de Comercio del Gobierno nacional no est\u00e1 controlando&#8221;. Adem\u00e1s, manifest\u00f3 que &#8220;las autoridades tienen que tomar cartas en el asunto, pero el Estado est\u00e1 con la actitud de que hay que dejar hacer, de que no hay que intervenir&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Por otro lado, reclam\u00f3 &#8220;la creaci\u00f3n de un laboratorio p\u00fablico de medicamentos en las distintas provincias y en la Naci\u00f3n, como existe en Santa Fe, que elabore los f\u00e1rmacos a menores precios y provea a los hospitales p\u00fablicos y a los centros de salud&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;El dinero que los consumidores dejan de pagar lo pueden invertir en la compra de otros bienes y servicios&#8221;, indic\u00f3 Polino. Una situaci\u00f3n similar ocurrir\u00eda con las arcas p\u00fablicas, ya que, seg\u00fan el especialista, &#8220;el Gobierno hoy provee a los hospitales medicamentos que le tiene que comprar a los laboratorios a estos precios exorbitantes, cosa que no ocurrir\u00eda si el Estado tuviera su propio laboratorio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una devaluaci\u00f3n de m\u00e1s del 50% en lo que va del a\u00f1o, los medicamentos en la Argentina ya subieron hasta 91% en s\u00f3lo tres meses, analizando los valores vigentes hasta abril respecto de los actuales. Un informe realizado por Consumidores Libres, a cargo de H\u00e9ctor Polino, compara los precios en los medicamentos y los n\u00fameros son exorbitantes. En tanto en la comparaci\u00f3n con 2015, los aumentos superan el 400% &nbsp; &nbsp; &nbsp; &nbsp; Los datos surgen del manual farmac\u00e9utico sobre 10 medicamentos de distintos grupos terap\u00e9uticos, entre los que&#8230;<\/p>\n","protected":false},"author":3,"featured_media":31137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/31136"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=31136"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/31136\/revisions"}],"predecessor-version":[{"id":31138,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/31136\/revisions\/31138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/31137"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=31136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=31136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=31136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}