{"id":26992,"date":"2018-05-14T11:51:44","date_gmt":"2018-05-14T14:51:44","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=26992"},"modified":"2018-11-06T19:46:11","modified_gmt":"2018-11-06T22:46:11","slug":"ater-implementa-el-domicilio-fiscal-electronico","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2018\/05\/14\/ater-implementa-el-domicilio-fiscal-electronico\/","title":{"rendered":"ATER implementa el Domicilio Fiscal Electr\u00f3nico"},"content":{"rendered":"<p><em><strong>La Administradora Tributaria de Entre R\u00edos (ATER) se sube al canal electr\u00f3nico, buscando fortalecer el control y agilizar los tiempos administrativos. Inicialmente alcanzar\u00e1 a grupos de grandes contribuyentes y agentes de retenci\u00f3n y percepci\u00f3n<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A trav\u00e9s de la Resol. 150\/18, La ATER anunci\u00f3 la puesta en vigencia del sistema Domicilio Fiscal Electr\u00f3nico.<\/p>\n<p>&nbsp;<\/p>\n<p>El titular de organismo, Sergio Granetto, afirm\u00f3: &#8220;Estamos avanzando fuertemente y en forma progresiva en modernizar las herramientas con las que cuenta ATER, ahora con el domicilio electr\u00f3nico y asociado a ello vendr\u00e1n la posibilidad de hacer planes de pago on line, el control fiscal electr\u00f3nico para cobranza y fiscalizaci\u00f3n, y varias novedades en el mismo sentido&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Luego manifest\u00f3 que \u201cestos son mejores servicios al contribuyente por un lado, y mejores herramientas para profundizar la cobranza a los grandes deudores de la provincia, que es hacia d\u00f3nde va primero esta medida\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>La nueva aplicaci\u00f3n permitir\u00e1 dinamizar las comunicaciones con los contribuyentes al realizarse \u00edntegramente v\u00eda Internet, portando validez y eficacia jur\u00eddica. De esta forma se logra que las notificaciones y avisos electr\u00f3nicos sean equiparables legalmente con el domicilio fiscal tradicional.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s, la nueva herramienta tiene un gran potencial en mejorar la comunicaci\u00f3n con cientos de contribuyentes con domicilio en otras provincias.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>El alcance ser\u00e1 segmentado y progresivo<\/strong><\/p>\n<p>Seg\u00fan se se\u00f1ala en la norma, la implementaci\u00f3n ser\u00e1 progresiva respecto de los plazos de adhesi\u00f3n al sistema y alcanzar\u00e1 inicialmente a tres grupos de contribuyentes nominados, entre los que se encuentran: Grandes Contribuyentes (Resol. 54\/17 ATER) hasta el 30 de junio de 2018; Agentes de retenci\u00f3n y percepci\u00f3n del impuesto a los Ingresos Brutos (Resol. ATER 319\/17) hasta el 30 de julio de 2018 y un nuevo segmento de Grandes Contribuyentes de impuestos de padr\u00f3n (Resol. ATER 149\/18) hasta el 31 de agosto de 2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Administradora Tributaria de Entre R\u00edos (ATER) se sube al canal electr\u00f3nico, buscando fortalecer el control y agilizar los tiempos administrativos. Inicialmente alcanzar\u00e1 a grupos de grandes contribuyentes y agentes de retenci\u00f3n y percepci\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; A trav\u00e9s de la Resol. 150\/18, La ATER anunci\u00f3 la puesta en vigencia del sistema Domicilio Fiscal Electr\u00f3nico. &nbsp; El titular de organismo, Sergio Granetto, afirm\u00f3: &#8220;Estamos avanzando fuertemente y en forma progresiva en modernizar las herramientas con las que cuenta ATER, ahora con el domicilio electr\u00f3nico y asociado a ello&#8230;<\/p>\n","protected":false},"author":3,"featured_media":9091,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/26992"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=26992"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/26992\/revisions"}],"predecessor-version":[{"id":26993,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/26992\/revisions\/26993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/9091"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=26992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=26992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=26992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}