{"id":26980,"date":"2018-05-08T11:03:26","date_gmt":"2018-05-08T14:03:26","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=26980"},"modified":"2018-11-06T19:46:11","modified_gmt":"2018-11-06T22:46:11","slug":"lula-mas-candidato-que-nunca-segun-el-teologo-leonardo-boff","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2018\/05\/08\/lula-mas-candidato-que-nunca-segun-el-teologo-leonardo-boff\/","title":{"rendered":"Lula, m\u00e1s candidato que nunca, seg\u00fan el te\u00f3logo Leonardo Boff"},"content":{"rendered":"<p><em><strong>El reconocido te\u00f3logo brasile\u00f1o Leonardo Boff visit\u00f3 ayer al ex presidente Luiz In\u00e1cio Lula da Silva, quien cumple un mes como preso pol\u00edtico y le pidi\u00f3 transmitir un recado: que es \u201ccandidat\u00edsimo\u201d para las pr\u00f3ximas elecciones<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Lula quiere volver al poder para dar prioridad a las pol\u00edticas p\u00fablicas volcadas hacia los pobres, sostuvo el tambi\u00e9n escritor en una improvisada conferencia de prensa luego de dejar la sede de la Superintendencia de la Polic\u00eda Federal (PF) en la ciudad de Curitiba, donde el ex dignatario permanece encerrado en una celda de aislamiento.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan Boff, Lula solo abandonar\u00e1 su candidatura el d\u00eda en que el juez federal S\u00e9rgio Moro logre presentar una \u00fanica prueba que sustente las acusaciones lanzadas contra \u00e9l.<\/p>\n<p>&nbsp;<\/p>\n<p>El encuentro entre dos viejos amigos dur\u00f3 aproximadamente una hora y media, relat\u00f3 el te\u00f3logo de la liberaci\u00f3n antes de afirmar que el fundador y l\u00edder hist\u00f3rico del Partido de los Trabajadores (PT) \u2018est\u00e1 muy bien, con disposici\u00f3n y vigor\u2019, rese\u00f1\u00f3 el diario digital Brasil 247.<\/p>\n<p>&nbsp;<\/p>\n<p>Coment\u00f3 adem\u00e1s que esa situaci\u00f3n de vivir en una \u2018solitaria\u2019 (celda de castigo), de solo poder conversar con los guardias que le traen la comida, hace que Lula lea y reflexione mucho.<\/p>\n<p>&nbsp;<\/p>\n<p>Semanas atr\u00e1s, Leonardo Boff fue impedido por la jueza federal de Paran\u00e1 Carolina Lebbos de hacerle una visita de car\u00e1cter humanitario y de asistencia religiosa a Lula, entonces en compa\u00f1\u00eda del de Premio Nobel de la Paz Adolfo P\u00e9rez Esquivel.<\/p>\n<p>&nbsp;<\/p>\n<p>En un art\u00edculo publicado hoy bajo el t\u00edtulo \u2018Hace 30 d\u00edas la esperanza del pueblo est\u00e1 presa\u2019, el sitio web www.lula.com.br cit\u00f3 palabras del ex presidente manifestando que desde hace un mes \u2018estoy aqu\u00ed aguardando que Moro y el TRF4 (tribunal de segunda instancia) digan qu\u00e9 delito comet\u00ed\u2019.<\/p>\n<p>&nbsp;<\/p>\n<p>El texto recuerda que en ese lapso, el l\u00edder petista transmiti\u00f3 diversos mensajes a la militancia, siempre demostrando tranquilidad y renovando las fuerzas de quienes desde el mismo 7 de abril est\u00e1n acampados en la capital de Paran\u00e1, protagonizando la vigilia democr\u00e1tica Lula Libre.<\/p>\n<p>&nbsp;<\/p>\n<p>Cuenta adem\u00e1s que las condiciones para el ba\u00f1o de sol de Lula s\u00f3lo fueron regularizadas en la Superintendencia de la PF una semana despu\u00e9s de su prisi\u00f3n, cuando los term\u00f3metros marcaban 15\u00c2\u00baC y ca\u00eda una lluvia sin tregua en Curitiba. \u2018No obstante, caminar\u00eda en c\u00edrculos bajo la lluvia por una hora y 10 minutos\u2019, detalla.<\/p>\n<p>&nbsp;<\/p>\n<p>Esta es la segunda vez que el ex dignatario enfrenta la arbitrariedad de una prisi\u00f3n pol\u00edtica \u2013 la primera durante la dictadura militar \u2013 puntualiza la publicaci\u00f3n, de acuerdo con la cual Curitiba, \u2018cada d\u00eda que pasa, ve m\u00e1s Lulas por las calles\u2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reconocido te\u00f3logo brasile\u00f1o Leonardo Boff visit\u00f3 ayer al ex presidente Luiz In\u00e1cio Lula da Silva, quien cumple un mes como preso pol\u00edtico y le pidi\u00f3 transmitir un recado: que es \u201ccandidat\u00edsimo\u201d para las pr\u00f3ximas elecciones &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Lula quiere volver al poder para dar prioridad a las pol\u00edticas p\u00fablicas volcadas hacia los pobres, sostuvo el tambi\u00e9n escritor en una improvisada conferencia de prensa luego de dejar la sede de la Superintendencia de la Polic\u00eda Federal (PF) en la ciudad de Curitiba, donde el ex dignatario permanece&#8230;<\/p>\n","protected":false},"author":3,"featured_media":26981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/26980"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=26980"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/26980\/revisions"}],"predecessor-version":[{"id":26982,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/26980\/revisions\/26982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/26981"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=26980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=26980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=26980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}