{"id":18976,"date":"2017-10-18T09:57:07","date_gmt":"2017-10-18T12:57:07","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=18976"},"modified":"2017-10-18T09:57:07","modified_gmt":"2017-10-18T12:57:07","slug":"francia-busca-tipificar-el-acoso-sexual-callejero-para-poder-penalizarlo","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/10\/18\/francia-busca-tipificar-el-acoso-sexual-callejero-para-poder-penalizarlo\/","title":{"rendered":"Francia busca tipificar el acoso sexual callejero para poder penalizarlo"},"content":{"rendered":"<p><em><strong>El Gobierno de Emmanuel Macron tambi\u00e9n busca debatir la prolongaci\u00f3n sobre el periodo de prescripci\u00f3n de los delitos sexuales contra menores y adem\u00e1s definir una edad m\u00ednima de consentimiento<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La secretaria de Estado para la Igualdad entre los hombres y las mujeres en Francia, Marl\u00e8ne Schiappa, ha anunciado este lunes los planes del Ejecutivo para presentar en 2018 un proyecto de ley \u201ccontra la violencia sexista y sexual\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s de tipificar el acoso callejero, el Gobierno de Macron busca poder prolongar el periodo de prescripci\u00f3n de los delitos de violencia sexual contra menores de 20 a 30 a\u00f1os y definir una edad de consentimiento para mantener relaciones sexuales.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan ha anunciado Schiappa en el diario La Croix, el Gobierno ha lanzado una \u201cgran consulta ciudadana\u201d sobre los temas de abuso para que as\u00ed\u00a0 \u201cla sociedad en su conjunto redefina qu\u00e9 es aceptable y qu\u00e9 no\u201d en materia de acoso sexual en la calle, una cuesti\u00f3n que se encuentra en una \u201czona gris entre la seducci\u00f3n consentida y la agresi\u00f3n sexual o la injuria p\u00fablica\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Hasta el pr\u00f3ximo 8 de marzo tendr\u00e1n lugar unos 300 talleres en todo el territorio franc\u00e9s mientras Schiappa elaborar\u00e1 el proyecto de ley junto con la ministra de Justicia, Nicole Belloubet en un di\u00e1logo abierto con la sociedad y sus diversos sectores.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Personalmente, pienso que silbarle a una mujer en la calle no supone acoso, pero que s\u00ed lo es si por ejemplo se la sigue hasta el metro. En ese caso, el estr\u00e9s, hasta la intimidaci\u00f3n, son evidentes\u201d, explica la responsable de la igualdad hombre-mujer del Gobierno de Macron en La Croix.<\/p>\n<p>&nbsp;<\/p>\n<p>La propia Schiappa reconoce adem\u00e1s que hay oposici\u00f3n entre algunas feministas y defensores de minor\u00edas que ven un \u201criesgo de racismo\u201d en esta ley porque, estad\u00edsticamente, ser\u00edan las personas de minor\u00edas las m\u00e1s susceptibles de ser m\u00e1s denunciadas que el resto.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s, la secretaria de Estado considera \u201cequilibrado\u201d en este sentido ampliar de 20 a 30 a\u00f1os a partir de la mayor\u00eda de edad de la v\u00edctima el periodo en que esta puede denunciar una agresi\u00f3n sexual.<\/p>\n<p>&nbsp;<\/p>\n<p>Schiappa tambi\u00e9n quiere que se establezca una edad m\u00ednima bajo la cual \u201cse presumir\u00e1 que un ni\u00f1o o adolescente no ha dado su consentimiento a un acto sexual\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Emmanuel Macron tambi\u00e9n busca debatir la prolongaci\u00f3n sobre el periodo de prescripci\u00f3n de los delitos sexuales contra menores y adem\u00e1s definir una edad m\u00ednima de consentimiento &nbsp; &nbsp; &nbsp; La secretaria de Estado para la Igualdad entre los hombres y las mujeres en Francia, Marl\u00e8ne Schiappa, ha anunciado este lunes los planes del Ejecutivo para presentar en 2018 un proyecto de ley \u201ccontra la violencia sexista y sexual\u201d. &nbsp; Adem\u00e1s de tipificar el acoso callejero, el Gobierno de Macron busca poder prolongar el periodo de prescripci\u00f3n de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":18977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/18976"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=18976"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/18976\/revisions"}],"predecessor-version":[{"id":18978,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/18976\/revisions\/18978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/18977"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=18976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=18976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=18976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}