{"id":18964,"date":"2017-10-18T09:52:30","date_gmt":"2017-10-18T12:52:30","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=18964"},"modified":"2017-10-18T09:52:30","modified_gmt":"2017-10-18T12:52:30","slug":"la-confesion-de-la-oposicion-a-nicolas-maduro-nos-derrotamos-nosotros-mismos","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/10\/18\/la-confesion-de-la-oposicion-a-nicolas-maduro-nos-derrotamos-nosotros-mismos\/","title":{"rendered":"La confesi\u00f3n de la oposici\u00f3n a Nicol\u00e1s Maduro: &#8220;Nos derrotamos nosotros mismos&#8221;"},"content":{"rendered":"<p><em><strong>Si bien en un primer momento algunas voces se alzaron contra los resultados obtenidos por el oficialismo en Venezuela en las elecciones regionales del pasado domingo, muchos otros no tuvieron m\u00e1s remedio que reconocer la derrota por su propia ineficiencia y programa pol\u00edtico<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Luego de algunas denuncias de fraude, la oposici\u00f3n venezolana comenz\u00f3 a reconocer los resultados de las urnas en las elecciones regionales con las que el chavismo se qued\u00f3 con 17 de las 23 gobernaciones.<\/p>\n<p>&nbsp;<\/p>\n<p>Excandidatos y l\u00edderes de la Mesa de la Unidad Democr\u00e1tica (MUD) de diferentes regiones del pa\u00eds, salieron a hacer un mea culpa sobre los resultados negativos obtenidos.<\/p>\n<p>&nbsp;<\/p>\n<p>Henri Falc\u00f3n, gobernador saliente y excandidato de la MUD por el estado de Lara, se\u00f1al\u00f3 que el resultado en las urnas del domingo es &#8220;tr\u00e1gico&#8221; y agreg\u00f3: &#8220;Responsablemente yo digo, nosotros perdimos, as\u00ed de sencillo y eso hay que aceptarlo porque tambi\u00e9n hay que tener gallard\u00eda&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;En 17 a\u00f1os, Amazonas camin\u00f3 en proyecto de los pueblos ind\u00edgenas y la democracia. (La) MUD en Caracas acab\u00f3 con ella imponiendo (un) candidato por sus intereses&#8221;, public\u00f3 el gobernador Liborio Guarulla en Twitter tras las elecciones.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Nos derrotamos nosotros mismos&#8221;, asegur\u00f3 el diputado opositor Jos\u00e9 Guerra que pidi\u00f3 reflexionar sobre la forma de hacer pol\u00edtica. En estas \u00faltimas elecciones la oposici\u00f3n obtuvo 11 puntos porcentuales menos en comparaci\u00f3n con el 56% de respaldo en comicios previos.<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte, el\u00a0 ex gobernador del estado de Miranda y uno de los principales opositores al Gobierno de Nicol\u00e1s Maduro, Henrique Capriles, se mantuvo en silencio sobre las denuncias de fraude y no se sum\u00f3 a las cr\u00edticas del accionar de la MUD.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si bien en un primer momento algunas voces se alzaron contra los resultados obtenidos por el oficialismo en Venezuela en las elecciones regionales del pasado domingo, muchos otros no tuvieron m\u00e1s remedio que reconocer la derrota por su propia ineficiencia y programa pol\u00edtico &nbsp; &nbsp; &nbsp; Luego de algunas denuncias de fraude, la oposici\u00f3n venezolana comenz\u00f3 a reconocer los resultados de las urnas en las elecciones regionales con las que el chavismo se qued\u00f3 con 17 de las 23 gobernaciones. &nbsp; Excandidatos y l\u00edderes de la Mesa de la Unidad&#8230;<\/p>\n","protected":false},"author":3,"featured_media":18965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/18964"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=18964"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/18964\/revisions"}],"predecessor-version":[{"id":18966,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/18964\/revisions\/18966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/18965"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=18964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=18964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=18964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}