{"id":18946,"date":"2017-10-18T09:47:13","date_gmt":"2017-10-18T12:47:13","guid":{"rendered":"http:\/\/actualidadadiario.com\/site\/?p=18946"},"modified":"2017-10-18T09:47:13","modified_gmt":"2017-10-18T12:47:13","slug":"milagro-sala-presentaron-habeas-corpus-y-recurso-ante-la-corte","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2017\/10\/18\/milagro-sala-presentaron-habeas-corpus-y-recurso-ante-la-corte\/","title":{"rendered":"Milagro Sala: presentaron h\u00e1beas corpus y recurso ante la Corte"},"content":{"rendered":"<p><em><strong>La defensa solicit\u00f3 que cese de manera inmediata su alojamiento en el penal de Alto Comedero, ya que &#8220;corre peligro&#8221; por el hostigamiento por parte de los penitenciarios<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La defensa de Milagro Sala realiz\u00f3 este martes una presentaci\u00f3n a la Corte Suprema de Justicia e interpuso un h\u00e1beas corpus ante el juez de turno en Jujuy a favor de la l\u00edder de la Tupac Amaru, para solicitar que cese de manera inmediata su alojamiento en el penal de Alto Comedero, tras advertir que su vida &#8220;corre peligro&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>En ambas peticiones, los abogados de Sala recordaron que la medida cautelar dispuesta por la Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) el 27 de julio pasado a\u00fan est\u00e1 vigente y reclamaron su cumplimiento.<\/p>\n<p>&nbsp;<\/p>\n<p>La defensa afirm\u00f3 que &#8220;hay mucha preocupaci\u00f3n por el estado de la dirigente social, el que claramente se ve agravado por nuevos hostigamientos de parte del personal del servicio penitenciario, quien en esta madruga la despert\u00f3 reiteradas veces sin ninguna raz\u00f3n&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>En los escritos, los letrados tambi\u00e9n resaltaron los motivos que llevaron a la CIDH a dictar la medida cautelar en virtud del da\u00f1o irreparable que podr\u00eda producir la permanencia de la dirigente social en la c\u00e1rcel de Alto Comedero.<\/p>\n<p>&nbsp;<\/p>\n<p>Se\u00f1alaron, adem\u00e1s, que la medida &#8220;se adopt\u00f3 tras corroborar por parte de los comisionados el nivel de hostigamiento al que fue sometida la dirigente social desde el 16 de enero de 2016 cuando, tal como lo determin\u00f3 el Grupo de Trabajo de Naciones Unidas, fue detenida en forma arbitraria&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>En la presentaci\u00f3n ante la Corte Suprema, la defensa de Sala inform\u00f3 sobre la situaci\u00f3n de la dirigente social y solicit\u00f3 al tribunal que se expida sobre los recursos extraordinarios que tiene en su poder desde abril pasado sobre la prisi\u00f3n preventiva de la l\u00edder de la Tupac Amaru, que cuentan con un dictamen favorable por parte de la Procuraci\u00f3n General de la Naci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Entendemos que la intervenci\u00f3n de V.E. en su condici\u00f3n de responsable m\u00e1ximo de la correcta administraci\u00f3n de justicia, debe actuar a fin de resguardar los derechos en juego de Milagro Sala&#8221;, se\u00f1alaron.<\/p>\n<p>&nbsp;<\/p>\n<p>Para los abogados, la resoluci\u00f3n emitida por el juez Pablo Pullen Llermanos el s\u00e1bado \u00faltimo, &#8220;es violatoria del leg\u00edtimo derecho a la defensa, adem\u00e1s de autocontradictoria, ya que cita informes del Departamento M\u00e9dico del Poder Judicial en los que recomienda que la dirigente social est\u00e9 en contacto las 24 horas con su familia dado el cuadro de depresi\u00f3n e ideaci\u00f3n suicida que presentaba&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La defensa solicit\u00f3 que cese de manera inmediata su alojamiento en el penal de Alto Comedero, ya que &#8220;corre peligro&#8221; por el hostigamiento por parte de los penitenciarios &nbsp; &nbsp; &nbsp; La defensa de Milagro Sala realiz\u00f3 este martes una presentaci\u00f3n a la Corte Suprema de Justicia e interpuso un h\u00e1beas corpus ante el juez de turno en Jujuy a favor de la l\u00edder de la Tupac Amaru, para solicitar que cese de manera inmediata su alojamiento en el penal de Alto Comedero, tras advertir que su vida &#8220;corre peligro&#8221;&#8230;.<\/p>\n","protected":false},"author":3,"featured_media":18947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/18946"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=18946"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/18946\/revisions"}],"predecessor-version":[{"id":18948,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/18946\/revisions\/18948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/18947"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=18946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=18946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=18946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}