{"id":136959,"date":"2026-05-13T09:26:56","date_gmt":"2026-05-13T12:26:56","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=136959"},"modified":"2026-05-13T09:26:56","modified_gmt":"2026-05-13T12:26:56","slug":"agmer-califico-de-practica-desleal-el-incremento-por-decreto","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2026\/05\/13\/agmer-califico-de-practica-desleal-el-incremento-por-decreto\/","title":{"rendered":"AGMER calific\u00f3 de &#8220;pr\u00e1ctica desleal&#8221; el incremento por decreto"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>La Asociaci\u00f3n Gremial del Magisterio de Entre R\u00edos (Agmer) declar\u00f3 la situaci\u00f3n de conflicto ante la falta de una nueva propuesta salarial por parte del gobierno provincial, al que acus\u00f3 de imponer de manera unilateral una oferta ya rechazada en paritarias y de vaciar de contenido el \u00e1mbito de negociaci\u00f3n<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>A trav\u00e9s de un comunicado, el gremio cuestion\u00f3 la decisi\u00f3n de la gesti\u00f3n del gobernador Rogelio Frigerio de oficializar mediante una resoluci\u00f3n la propuesta salarial rechazada durante la reuni\u00f3n paritaria del pasado 7 de mayo. Denuncia que la medida representa una \u201cpr\u00e1ctica desleal\u201d y contradice el discurso oficial de mantener abiertas las negociaciones.<\/p>\n<p>Desde el gremio se\u00f1alaron que la oferta no contempla una recuperaci\u00f3n real del poder adquisitivo de los docentes, afectado por la aceleraci\u00f3n del costo de vida. En ese sentido, remarcaron que el salario contin\u00faa perdiendo frente a la inflaci\u00f3n y reclamaron una propuesta \u201cdigna\u201d que evite que los trabajadores de la educaci\u00f3n sean \u201cla variable de ajuste\u201d.<\/p>\n<p>El gremio tambi\u00e9n defendi\u00f3 el \u00e1mbito paritario. \u201cVolvemos a decir que valoramos y defendemos cada espacio de di\u00e1logo donde llevamos la voz y el reclamo de los trabajadores de la educaci\u00f3n, donde debemos ser escuchados y obtener la respuesta que deben a la escuela p\u00fablica y los trabajadores de la educaci\u00f3n. Valoramos y defendemos la instituci\u00f3n de la paritaria, cuyo valor reside en ser un \u00e1mbito en el que trabajadores y patronal nos encontramos a dialogar en condici\u00f3n de paridad\u201d, expuso Agmer. A la vez, advirti\u00f3 que \u201cla pol\u00edtica y las pr\u00e1cticas del gobierno vac\u00edan de sentido al \u00e1mbito paritario y minan la confianza necesaria para la discusi\u00f3n y construcci\u00f3n democr\u00e1tica\u201d.<\/p>\n<p>En el marco de la Ley 9.624 de Convenci\u00f3n Colectiva de Trabajo Docente, Agmer resolvi\u00f3 declarar formalmente la situaci\u00f3n de conflicto frente al Estado provincial \u201cpara que se habilite una situaci\u00f3n de negociaci\u00f3n real\u201d. Adem\u00e1s, exigi\u00f3 voluntad pol\u00edtica del Ejecutivo para destrabar el conflicto salarial y responder a las demandas del sector docente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n Gremial del Magisterio de Entre R\u00edos (Agmer) declar\u00f3 la situaci\u00f3n de conflicto ante la falta de una nueva propuesta salarial por parte del gobierno provincial, al que acus\u00f3 de imponer de manera unilateral una oferta ya rechazada en paritarias y de vaciar de contenido el \u00e1mbito de negociaci\u00f3n &nbsp; &nbsp; A trav\u00e9s de un comunicado, el gremio cuestion\u00f3 la decisi\u00f3n de la gesti\u00f3n del gobernador Rogelio Frigerio de oficializar mediante una resoluci\u00f3n la propuesta salarial rechazada durante la reuni\u00f3n paritaria del pasado 7 de mayo. Denuncia que la&#8230;<\/p>\n","protected":false},"author":3,"featured_media":120755,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/136959"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=136959"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/136959\/revisions"}],"predecessor-version":[{"id":136960,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/136959\/revisions\/136960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/120755"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=136959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=136959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=136959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}