{"id":123018,"date":"2024-11-22T12:01:05","date_gmt":"2024-11-22T15:01:05","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=123018"},"modified":"2024-11-22T12:01:05","modified_gmt":"2024-11-22T15:01:05","slug":"starlink-la-empresa-de-elon-musk-desembarca-en-las-escuelas-rurales-cordobesas","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2024\/11\/22\/starlink-la-empresa-de-elon-musk-desembarca-en-las-escuelas-rurales-cordobesas\/","title":{"rendered":"Starlink, la empresa de Elon Musk, desembarca en las escuelas rurales cordobesas"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>El gobierno de C\u00f3rdoba acord\u00f3 con Starlink la provisi\u00f3n de conectividad para 860 escuelas rurales. La \u201ccomplejidad geoestrat\u00e9gica\u201d que implica una soluci\u00f3n que llega de la mano de Elon Musk y no, por ejemplo, de Arsat. Las voces que valoran la medida<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El anuncio compartido entre el gobierno de Mart\u00edn Llaryora y la empresa de Elon Musk contempla cubrir con internet satelital al 65% del total de las escuelas rurales que existen en la provincia de C\u00f3rdoba. De ese modo, el servicio podr\u00eda beneficiar a cerca de 40.000 ni\u00f1as, ni\u00f1os y adolescentes.<\/p>\n<p>Fuentes del \u00e1rea de telecomunicaciones del gobierno cordob\u00e9s justificaron la decisi\u00f3n como un intento por revertir \u201cla falta de inversi\u00f3n de los anteriores gobiernos de la provincia\u201d y \u201cel desguace de las pol\u00edticas del kirchnerismo en el \u00e1rea, tanto en el Enacom como en Arsat\u201d.<\/p>\n<p>Ante la falta de inversi\u00f3n previa para generar redes de soberan\u00eda tecnol\u00f3gica (como sucedi\u00f3 en su momento en La Rioja o San Luis), el acuerdo con Starlink refleja un pragmatismo que deja de lado lo que representa la empresa en t\u00e9rminos simb\u00f3licos a nivel global. La contrataci\u00f3n se est\u00e1 desarrollando en paralelo con la extensi\u00f3n de la red de fibra \u00f3ptica, seg\u00fan explican desde el gobierno provincial. Ese proceso durar\u00e1 por los menos dos a\u00f1os, por lo que, por el momento, Starlink surge como la mejor opci\u00f3n.<\/p>\n<p>La noticia provoc\u00f3 distintas miradas entre educadores populares y organizaciones sociales que d\u00eda a d\u00eda luchan por otro mundo posible.<\/p>\n<p>M\u00e1s all\u00e1 del modelo hegem\u00f3nico empresarial (cada vez m\u00e1s concentrado) y del papel simb\u00f3lico y geopol\u00edtico que representa el due\u00f1o de Stralink, Elon Musk,\u00a0 diversos referentes tecnol\u00f3gicos y comunitarios se pronunciaron a favor del acuerdo.<\/p>\n<p>Diego Rossi, profesor de Pol\u00edticas de Comunicaci\u00f3n de la UBA y miembro de la Coalici\u00f3n para una Comunicaci\u00f3n Democr\u00e1tica, explica la complejidad de la situaci\u00f3n: \u201cLa mirada del gobierno cordob\u00e9s es razonable, en la medida que tiende a resolver algo que podr\u00eda haber resuelto el Enacom en su momento. Pero eran costos muy altos y esto de alguna manera hace sentido con una mirada de auditor\u00eda que el actual gobierno de Milei pos\u00f3 sobre algunas contrataciones de conectividad satelital del Ministerio de Educaci\u00f3n y del propio Enacom\u201d.<\/p>\n<p>Musk es el palad\u00edn tecnol\u00f3gico de las nuevas derechas, suena como pr\u00f3ximo funcionario de la Casa Blanca, en la pr\u00f3xima administraci\u00f3n Trump, pero su empresa satelital tendr\u00e1 una presencia que podr\u00eda haber disputado el Estado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Entre la geopol\u00edtica y la realidad<\/strong><\/p>\n<p>\u201cEvidentemente hay cosas con las que Starlink no tiene competencia, como es el caso de los sat\u00e9lites de \u00f3rbita baja. Me encantar\u00eda que hubiera m\u00e1s elementos que nos diera nuestro Estado nacional, ya que la constelaci\u00f3n de Starlink, desde que se lanz\u00f3, la vimos como una amenaza a la soberan\u00eda tecnol\u00f3gica. Pero no podemos hacer mucho\u201d, se lamenta Rossi. Y justifica: \u201cEl plan satelital de Arsat se demor\u00f3 durante el gobierno de Macri, con Alberto se ralentiz\u00f3 y Milei lo va a planchar. Con lo cual, aun cuando se corrija esta pol\u00edtica, eso demorar\u00e1 algunos a\u00f1os. Podr\u00edamos seguir dejando escuelas desconectadas o pagar abonos caros con otras empresas, tambi\u00e9n transnacionales. F\u00e1cticamente resulta comprensible que una parte de achicar la brecha en Argentina hoy sea este tipo de contrataciones\u201d.<\/p>\n<p>Los planes de Starlink cuestan en Argentina lo mismo que en Brasil, y la mitad o un tercio del precio que se paga en Estados Unidos. Esto puede deberse a decisiones ideol\u00f3gicas o geopol\u00edticas (por la expectativa de acceso al litio en Argentina por parte de Elon Musk). Tambi\u00e9n, a una t\u00e9cnica de dumping (reducir los precios para dominar el mercado). Lo cierto es que, adem\u00e1s del margen econ\u00f3mico que tiene la empresa por su desarrollo tecnol\u00f3gico, tampoco existen demasiados competidores, y el pa\u00eds no cuenta con una Comisi\u00f3n de Defensa de la Competencia que funcione como tal. Como el Estado no puede regular este servicio, la situaci\u00f3n se parece a la de otros servicios p\u00fablicos: un monopolio \u201cnatural\u201d.<\/p>\n<p>\u201cLas escuelas rurales de C\u00f3rdoba hist\u00f3ricamente tienen servicios que no funcionan. Nosotros lo que estamos tratando de ver es c\u00f3mo aprovechar el hecho de tener una conectividad razonable para facilitar redes comunitarias que hagan accesible el servicio para todes. De hecho, ya lo venimos desarrollando con la se\u00f1al de Starlink en Jos\u00e9 de la Quintana\u201d, aclara Nicol\u00e1s Echaniz, socio de Alter Mundi, una cooperativa tecnol\u00f3gica que viene implementando proyectos de conectividad y libre router junto a organizaciones de peque\u00f1os y medianos productores rurales como la Uni\u00f3n de Trabajadoras Rurales (UTR).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La lejana ruralidad<\/strong><\/p>\n<p>\u201cDesde la Comuna venimos desarrollando el trabajo en una escuelita dentro de una reserva h\u00eddrica natural, donde los chicos est\u00e1n rodeados de la naturaleza, aprendiendo de todo lo que es el entorno, pero tambi\u00e9n atravesados por este mundo en el que vivimos, donde las tecnolog\u00edas tambi\u00e9n son parte del cotidiano y son necesarias. As\u00ed que ven\u00edamos pidiendo esa conexi\u00f3n\u201d, cuenta Natalia Di Pace, jefa comunal de Villa Cerro Azul y parte del Movimiento Verde Cordob\u00e9s (MVC). \u201cEs parte de estas contradicciones y tensiones en las que vivimos. El desaf\u00edo est\u00e1 en c\u00f3mo poder utilizar las tecnolog\u00edas y lo que se llama a veces progreso. Nuestro proyecto pol\u00edtico est\u00e1 orientado a ese equilibrio entre preservar la comunidad y la naturaleza, pero tambi\u00e9n siendo conscientes del mundo en el que vivimos, donde no tenerlo tambi\u00e9n nos aleja y nos imposibilita entramarnos para hacer un mundo mejor\u201d, aclara.<\/p>\n<p>\u201cAl f\u00fatbol podemos jugar con pelotas de trapo, pero programar y subir data con una mala conectividad se vuelve complejo\u201d, relata Anselmo Cunill, m\u00fasico, soci\u00f3logo e investigador de Traslasierra que viene desarrollando cursos de formaci\u00f3n en tecnolog\u00eda en escuelas rurales y es parte del equipo de Futurx, un centro de investigaci\u00f3n y desarrollo que hace poco public\u00f3 el libro IA + M\u00fasica.<\/p>\n<p>\u201c\u00bfPor qu\u00e9 Starlink y no Arsat?\u201d, se pregunta Cunill. \u201cAh\u00ed hay una complejidad geoestrat\u00e9gica. Yo soy usuario de Starlink, no porque me caiga bien Elon Musk, sino porque donde vivo, por los requerimientos que tengo de conectividad, era la \u00fanica opci\u00f3n. Otra cosa son los proyectos globales de transici\u00f3n energ\u00e9tica y qu\u00e9 color pol\u00edtico van tomando, sabiendo el tipo de sociedad y de planeta que est\u00e1n imaginando. Son proyectos de una concentraci\u00f3n econ\u00f3mica muy fuerte, de una desigualdad muy fuerte. Son proyectos que da\u00f1an o perjudican o van en contra de las soberan\u00edas, sean territoriales, alimentarias o tecnol\u00f3gicas. Entonces, es bravo\u201d, concluye el investigador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de C\u00f3rdoba acord\u00f3 con Starlink la provisi\u00f3n de conectividad para 860 escuelas rurales. La \u201ccomplejidad geoestrat\u00e9gica\u201d que implica una soluci\u00f3n que llega de la mano de Elon Musk y no, por ejemplo, de Arsat. Las voces que valoran la medida &nbsp; &nbsp; El anuncio compartido entre el gobierno de Mart\u00edn Llaryora y la empresa de Elon Musk contempla cubrir con internet satelital al 65% del total de las escuelas rurales que existen en la provincia de C\u00f3rdoba. De ese modo, el servicio podr\u00eda beneficiar a cerca de 40.000&#8230;<\/p>\n","protected":false},"author":3,"featured_media":123019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123018"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=123018"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123018\/revisions"}],"predecessor-version":[{"id":123020,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123018\/revisions\/123020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/123019"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=123018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=123018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=123018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}