{"id":123014,"date":"2024-11-22T11:59:02","date_gmt":"2024-11-22T14:59:02","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=123014"},"modified":"2024-11-22T11:59:02","modified_gmt":"2024-11-22T14:59:02","slug":"el-calendario-oficial-de-feriados-para-2025-en-argentina","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2024\/11\/22\/el-calendario-oficial-de-feriados-para-2025-en-argentina\/","title":{"rendered":"El calendario oficial de feriados para 2025 en Argentina"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>A trav\u00e9s del Decreto 1027\/2024, el Gobierno confirm\u00f3 qu\u00e9 d\u00edas no ser\u00e1n laborables el a\u00f1o pr\u00f3ximo con fines tur\u00edsticos<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El Gobierno oficializ\u00f3 el calendario de feriados para 2025, a trav\u00e9s del Decreto 1027\/2024 publicado en el Bolet\u00edn Oficial. De este modo se confirm\u00f3 qu\u00e9 d\u00edas no ser\u00e1n laborables con fines tur\u00edsticos el pr\u00f3ximo a\u00f1o, como as\u00ed tambi\u00e9n cu\u00e1ntos fin de semana largos habr\u00e1, para aprovechar y planificar las vacaciones.<\/p>\n<p>El decreto lleva la firma tanto del presidente Javier Milei como del jefe de Gabinete, Guillermo Francos y se ampara en el art\u00edculo 6\u00b0 de la Ley N\u00b0 27.399 que otorga la facultad al Ejecutivo de fijar anualmente hasta tres d\u00edas feriados o no laborables destinados a promover la actividad tur\u00edstica y que deben coincidir con los d\u00edas lunes o viernes.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Feriados 2025: qu\u00e9 d\u00edas ser\u00e1n no laborables<\/strong><\/p>\n<p>De esta forma, el primer d\u00eda no laborable definido con fines tur\u00edsticos, fue asignado para el viernes 2 de mayo, el cual complementa el feriado nacional que ser\u00e1 el jueves 1 de mayo, el D\u00eda Internacional del Trabajador en conmemoraci\u00f3n de la sangrienta represi\u00f3n que sufrieran los obreros de la f\u00e1brica McCormick, durante varios d\u00edas de abril y mayo de 1886, en la ciudad de Chicago, con la intenci\u00f3n de ser una oportunidad para afirmar sus derechos y su mutua solidaridad.<\/p>\n<p>El segundo llega tres meses despu\u00e9s. Precisamente, el viernes 15 de agosto a ra\u00edz del feriado del 17 de ese mes en el que se conmemora el paso a la inmortalidad del general Jos\u00e9 de San Mart\u00edn y que se traslada para el lunes 18, coincidiendo con el D\u00eda del Ni\u00f1o.<\/p>\n<p>El \u00faltimo se design\u00f3 para el viernes 21 de noviembre, pegado al jueves 20, jornada en la que se conmemora el D\u00eda de la Soberan\u00eda Nacional en homenaje a la batalla de la Vuelta de Obligado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Feriados puente como no laborables<\/strong><\/p>\n<p>El Gobierno, a trav\u00e9s de la medida, decidi\u00f3 que los definidos como feriados puente, no sean precisamente feriados, sino d\u00edas no laborables. Esto implica que la decisi\u00f3n de si una persona trabaja o no queda en manos del empleador y no es una obligaci\u00f3n dejarle el d\u00eda libre.<\/p>\n<p>En tanto, en un feriado nacional, las normas de descanso dominical rigen de manera obligatoria, y en caso de trabajar en esas jornadas, la remuneraci\u00f3n del d\u00eda se duplica, es decir, se paga el doble.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Los feriados del 2025:<\/strong><\/p>\n<ul>\n<li>Mi\u00e9rcoles 1 de enero: A\u00f1o nuevo<\/li>\n<li>Lunes 3 y martes 4 de marzo: Carnaval<\/li>\n<li>Lunes 24 de marzo: D\u00eda de la Memoria Nacional<\/li>\n<li>Mi\u00e9rcoles 2 de abril: D\u00eda del Veterano y de los Ca\u00eddos en la Guerra de Malvinas)<\/li>\n<li>Jueves 17 y viernes 18 de abril: Semana Santa<\/li>\n<li>Jueves 1 de mayo: D\u00eda Internacional del Trabajador<\/li>\n<li>Viernes 2 de mayo: feriado puente<\/li>\n<li>Domingo 25 de mayo: D\u00eda de la Revoluci\u00f3n de Mayo<\/li>\n<li>Viernes 20 de junio: Paso a la Inmortalidad del General Manuel Belgrano<\/li>\n<li>Mi\u00e9rcoles 9 de julio: D\u00eda de la Independencia<\/li>\n<li>Viernes 15 de agosto: feriado puente<\/li>\n<li>Lunes 18 de agosto: trasladado del domingo 17 que se conmemora el Paso a la Inmortalidad del Gral. Jos\u00e9 de San Mart\u00edn<\/li>\n<li>Domingo 12 de octubre: D\u00eda del Respeto a la Diversidad Cultural<\/li>\n<li>Jueves 20 de noviembre: D\u00eda de la Soberan\u00eda Nacional<\/li>\n<li>Viernes 21 de noviembre: feriado puente<\/li>\n<li>Lunes 8 de diciembre: D\u00eda de la Inmaculada Concepci\u00f3n de Mar\u00eda<\/li>\n<li>Jueves 25 de diciembre: Navidad<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Los feriados puente del 2025:<\/strong><\/p>\n<p>Los feriados puente resueltos en el Decreto 1027\/2024 por el Gobierno Nacional son:<\/p>\n<ul>\n<li>Viernes 2 de mayo<\/li>\n<li>Viernes 15 de agosto<\/li>\n<li>Viernes 21 de noviembre<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s del Decreto 1027\/2024, el Gobierno confirm\u00f3 qu\u00e9 d\u00edas no ser\u00e1n laborables el a\u00f1o pr\u00f3ximo con fines tur\u00edsticos &nbsp; &nbsp; El Gobierno oficializ\u00f3 el calendario de feriados para 2025, a trav\u00e9s del Decreto 1027\/2024 publicado en el Bolet\u00edn Oficial. De este modo se confirm\u00f3 qu\u00e9 d\u00edas no ser\u00e1n laborables con fines tur\u00edsticos el pr\u00f3ximo a\u00f1o, como as\u00ed tambi\u00e9n cu\u00e1ntos fin de semana largos habr\u00e1, para aprovechar y planificar las vacaciones. El decreto lleva la firma tanto del presidente Javier Milei como del jefe de Gabinete, Guillermo Francos y se&#8230;<\/p>\n","protected":false},"author":3,"featured_media":122212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123014"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=123014"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123014\/revisions"}],"predecessor-version":[{"id":123015,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123014\/revisions\/123015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/122212"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=123014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=123014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=123014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}