{"id":123008,"date":"2024-11-22T10:43:40","date_gmt":"2024-11-22T13:43:40","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=123008"},"modified":"2024-11-22T10:43:40","modified_gmt":"2024-11-22T13:43:40","slug":"desde-este-sabado-nuevo-aumento-en-el-peaje-de-la-ruta-14","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2024\/11\/22\/desde-este-sabado-nuevo-aumento-en-el-peaje-de-la-ruta-14\/","title":{"rendered":"Desde este s\u00e1bado, nuevo aumento en el peaje de la ruta 14"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>La ruta 14 tendr\u00e1 nuevos valores en los peajes desde este s\u00e1bado, precis\u00f3 Caminos del R\u00edo Uruguay. Ya se conocen los nuevos precios<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Caminos del R\u00edo Uruguay, la empresa concesionaria de la ruta 14, anunci\u00f3 un aumento en el peaje del Corredor N\u00b018 de la Autov\u00eda Jos\u00e9 Gervasio Artigas, que entrar\u00e1 en vigencia este s\u00e1bado 23 de noviembre.<\/p>\n<p>El incremento ser\u00e1 aplicable a partir del primer minuto de ese d\u00eda, una vez que se haya dado a conocer la novedad &#8220;a los usuarios, mediante su publicaci\u00f3n en formato papel o digital durante dos d\u00edas consecutivos, como lo establece la normativa&#8221;. Tal como ocurri\u00f3 en aumentos anteriores, las tarifas para el pago manual se redondear\u00e1n a m\u00faltiplos de $100 para facilitar la gesti\u00f3n en las cabinas de cobro. De este modo, la tarifa de la categor\u00eda 1, correspondiente a autos generales, pasar\u00e1 de $800 a $900 en las cabinas ubicadas en la Ruta Nacional 14.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Nuevo esquema tarifario:<\/strong><\/p>\n<ul>\n<li>Categor\u00eda 1: Manual: $900 &#8211; Telepase: $810,24<\/li>\n<li>Categor\u00eda 2: Manual: $1700 &#8211; Telepase: $1620,48<\/li>\n<li>Categor\u00eda 3: Manual: $1700 &#8211; Telepase: $1620,48<\/li>\n<li>Categor\u00eda 4: Manual: $2500 &#8211; Telepase: $2430,72<\/li>\n<li>Categor\u00eda 5: Manual: $3300 &#8211; Telepase: $3240,96<\/li>\n<li>Categor\u00eda 6: Manual: $3300 &#8211; Telepase: $3240,96<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La ruta 14 tendr\u00e1 nuevos valores en los peajes desde este s\u00e1bado, precis\u00f3 Caminos del R\u00edo Uruguay. Ya se conocen los nuevos precios &nbsp; &nbsp; Caminos del R\u00edo Uruguay, la empresa concesionaria de la ruta 14, anunci\u00f3 un aumento en el peaje del Corredor N\u00b018 de la Autov\u00eda Jos\u00e9 Gervasio Artigas, que entrar\u00e1 en vigencia este s\u00e1bado 23 de noviembre. El incremento ser\u00e1 aplicable a partir del primer minuto de ese d\u00eda, una vez que se haya dado a conocer la novedad &#8220;a los usuarios, mediante su publicaci\u00f3n en formato&#8230;<\/p>\n","protected":false},"author":3,"featured_media":36977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123008"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=123008"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123008\/revisions"}],"predecessor-version":[{"id":123009,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123008\/revisions\/123009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/36977"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=123008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=123008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=123008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}