{"id":123000,"date":"2024-11-22T10:40:31","date_gmt":"2024-11-22T13:40:31","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=123000"},"modified":"2024-11-22T10:40:31","modified_gmt":"2024-11-22T13:40:31","slug":"senalan-que-son-cada-vez-mas-las-familias-atendidas-en-comedores-y-merenderos-de-concordia","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2024\/11\/22\/senalan-que-son-cada-vez-mas-las-familias-atendidas-en-comedores-y-merenderos-de-concordia\/","title":{"rendered":"Se\u00f1alan que son cada vez m\u00e1s las familias atendidas en comedores y merenderos de Concordia"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>El director diocesano de C\u00e1ritas Concordia, Pedro Sena, se refiri\u00f3 a la creciente demanda de ayuda en comedores y merenderos de Concordia. &#8220;A principio de a\u00f1o ten\u00edamos un promedio de 60 familias en ciertas comunidades y hoy tenemos 180 porque no logran llegar a fin de mes\u201d<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Sena expres\u00f3 que la demanda ha crecido de manera alarmante: &#8220;Antes ten\u00edamos cientos de personas, pero la cifra sigue subiendo. Muchos comedores y merenderos ya no reciben asistencia como antes y varios han tenido que cerrar\u201d, precis\u00f3.<\/p>\n<p>C\u00e1ritas tambi\u00e9n lleva a cabo censos para actualizar su registro de familias beneficiarias y de este modo enfocar mejor los recursos. &#8220;La situaci\u00f3n econ\u00f3mica y las malas cosechas han dejado a muchos en una situaci\u00f3n cr\u00edtica&#8221;, explic\u00f3.<\/p>\n<p>Subray\u00f3 que C\u00e1ritas no solo distribuye alimentos y ropa. &#8220;La misi\u00f3n de C\u00e1ritas es la promoci\u00f3n humana. Queremos que las personas puedan recuperar su dignidad, tener trabajo, documentos, acceso a educaci\u00f3n y otros derechos b\u00e1sicos. En algunas parroquias se han levantado viviendas realizadas y ferias para ayudar a cubrir estas necesidades&#8221;, se\u00f1al\u00f3.<\/p>\n<p>Sobre el aporte del Estado, revel\u00f3 en declaraciones radiales que \u201chubo muchas asistencias que estuvieron cortadas, pero se fueron abriendo o est\u00e1n surgiendo nuevamente\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>C\u00f3mo colaborar con C\u00e1ritas<\/strong><\/p>\n<p>Sena hizo un llamado a quienes desearan colaborar: &#8220;Concordia no se conmueve \u00fanicamente, sino que se mueve. Concordia es una ciudad muy solidaria. Cualquiera que quiera ayudar puede acercarse a su parroquia o a nuestra sede en La Paz 831, donde se atiende de 8 a 12 y de 16 a 20. C\u00e1ritas es un mundo que necesitar\u00eda muchas charlas para abarcarlo por completo&#8221;, expres\u00f3.<\/p>\n<p>Y finaliz\u00f3: &#8220;Lo que aconsejamos a quien quiera colaborar es que se acerque a su comunidad parroquial y arrime lo que quiera, o se pueda presentar y diga estoy disponible para esto o c\u00f3mo puedo acompa\u00f1ar un fin de semana, primero en la comunidad que le corresponde&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director diocesano de C\u00e1ritas Concordia, Pedro Sena, se refiri\u00f3 a la creciente demanda de ayuda en comedores y merenderos de Concordia. &#8220;A principio de a\u00f1o ten\u00edamos un promedio de 60 familias en ciertas comunidades y hoy tenemos 180 porque no logran llegar a fin de mes\u201d &nbsp; &nbsp; Sena expres\u00f3 que la demanda ha crecido de manera alarmante: &#8220;Antes ten\u00edamos cientos de personas, pero la cifra sigue subiendo. Muchos comedores y merenderos ya no reciben asistencia como antes y varios han tenido que cerrar\u201d, precis\u00f3. C\u00e1ritas tambi\u00e9n lleva a&#8230;<\/p>\n","protected":false},"author":3,"featured_media":117326,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123000"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=123000"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123000\/revisions"}],"predecessor-version":[{"id":123001,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/123000\/revisions\/123001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/117326"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=123000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=123000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=123000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}