{"id":122958,"date":"2024-11-20T15:17:41","date_gmt":"2024-11-20T18:17:41","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=122958"},"modified":"2024-11-20T15:17:41","modified_gmt":"2024-11-20T18:17:41","slug":"diputados-del-pro-presentaron-un-proyecto-para-derogar-la-ley-de-etiquetado-frontal","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2024\/11\/20\/diputados-del-pro-presentaron-un-proyecto-para-derogar-la-ley-de-etiquetado-frontal\/","title":{"rendered":"Diputados del PRO presentaron un proyecto para derogar la Ley de Etiquetado Frontal"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>Buscan eliminar la ley a trav\u00e9s de la cual se informa a los consumidores sobre los nutrientes cr\u00edticos en los alimentos por considerar que &#8220;confunde&#8221; y &#8220;entorpece&#8221; el comercio internacional de productos argentinos<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Los diputados del PRO Alejandro Bongiovanni y Daiana Fern\u00e1ndez Molero presentaron un proyecto de ley con el fin de derogar la Ley N\u00b0 27.642, m\u00e1s conocida como &#8220;Ley de etiquetado frontal de alimentos&#8221;, que advierte a los consumidores sobre los excesos de componentes como az\u00facares, sodio, grasas saturadas, grasas totales y calor\u00edas.<\/p>\n<p>Con un video publicado en X, anunciaron: &#8220;Vamos a derogar la Ley de Etiquetado Frontal. Es una mala ley, excesivamente paternalista que no sirve, no te informa. Porque si todo tiene sello, es como si nada tuviera sello. Este es el Estado tratando al consumidor no solo como un ni\u00f1o, sino como un ni\u00f1o medio idiota&#8221;.<\/p>\n<p>El proyecto se\u00f1ala que el objetivo es \u201cla restituci\u00f3n de la libertad de productores y consumidores de alimentos, mediante la derogaci\u00f3n del R\u00e9gimen de Etiquetado Frontal Ley N\u00b0 27.642, cuyos objetivos se cumplen de modo m\u00e1s eficaz con la normativa ya vigente en el C\u00f3digo Alimentario en relaci\u00f3n a rotulado, comercializaci\u00f3n e informaci\u00f3n\u201d.<\/p>\n<p>Adem\u00e1s, se indica que &#8220;desde un punto de vista econ\u00f3mico o financiero el proyecto no tiene costo fiscal, no requiriendo fuente de financiamiento&#8221;.<\/p>\n<p>\u201cEl universo de potenciales beneficiarios abarca a productores, exportadores, importadores y comercializadores de los alimentos alcanzados por la Ley N\u00b0 27.642, y a sus consumidores\u201d, concluyeron.<\/p>\n<p>El objetivo de la Ley de Etiquetado Frontal sancionada en 2021 era prevenir la malnutrici\u00f3n y enfermedades cr\u00f3nicas no transmisibles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buscan eliminar la ley a trav\u00e9s de la cual se informa a los consumidores sobre los nutrientes cr\u00edticos en los alimentos por considerar que &#8220;confunde&#8221; y &#8220;entorpece&#8221; el comercio internacional de productos argentinos &nbsp; &nbsp; Los diputados del PRO Alejandro Bongiovanni y Daiana Fern\u00e1ndez Molero presentaron un proyecto de ley con el fin de derogar la Ley N\u00b0 27.642, m\u00e1s conocida como &#8220;Ley de etiquetado frontal de alimentos&#8221;, que advierte a los consumidores sobre los excesos de componentes como az\u00facares, sodio, grasas saturadas, grasas totales y calor\u00edas. Con un video&#8230;<\/p>\n","protected":false},"author":3,"featured_media":102719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/122958"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=122958"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/122958\/revisions"}],"predecessor-version":[{"id":122959,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/122958\/revisions\/122959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/102719"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=122958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=122958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=122958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}