{"id":122950,"date":"2024-11-20T14:39:51","date_gmt":"2024-11-20T17:39:51","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=122950"},"modified":"2024-11-20T14:39:51","modified_gmt":"2024-11-20T17:39:51","slug":"la-universidad-de-buenos-aires-abrio-las-inscripciones-para-el-2025-como-y-donde-anotarse","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2024\/11\/20\/la-universidad-de-buenos-aires-abrio-las-inscripciones-para-el-2025-como-y-donde-anotarse\/","title":{"rendered":"La Universidad de Buenos Aires abri\u00f3 las inscripciones para el 2025: c\u00f3mo y d\u00f3nde anotarse"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><em>Las inscripciones para alumnos al Ciclo B\u00e1sico Com\u00fan 2025 y a UBA XXI abrieron hoy y continuar\u00e1n hasta el 29 de noviembre. Esta instancia apunta a todas las personas que inicien una carrera por primera vez<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La Universidad de Buenos Aires (UBA) abre sus primeras etapas de inscripci\u00f3n de cara al ciclo lectivo de 2025. Desde hoy y hasta el 29 de noviembre estar\u00e1 abierta la inscripci\u00f3n al Ciclo B\u00e1sico Com\u00fan y a UBA XXI para alumnos que nunca se hayan anotado en la universidad.<\/p>\n<p>El proceso de inscripci\u00f3n a la Universidad de Buenos Aires consta de un total de tres pasos: preinscripci\u00f3n online (que comienza hoy), presentaci\u00f3n de la documentaci\u00f3n, y selecci\u00f3n de sede y turno en la web del CBC. El ingreso a la UBA es irrestricto y sin examen de ingreso, para realizar el proceso de inscripci\u00f3n, se necesita tener el DNI argentino vigente.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>UBA: \u00bfQu\u00e9 es el CBC?<\/strong><\/p>\n<p>Es Ciclo B\u00e1sico Com\u00fan es el primer a\u00f1o que debe cursarse en todas las carreras de la Universidad de Buenos Aires, sin importar su orientaci\u00f3n. El ciclo consta de seis materias (asignaturas).<\/p>\n<p>En detalle, dos de esas materias son comunes a todas las carreras (Introducci\u00f3n al Pensamiento Cient\u00edfico e Introducci\u00f3n al Conocimiento de la Sociedad y el Estado) dos seg\u00fan la orientaci\u00f3n, dos espec\u00edficas de la carrera.<\/p>\n<p>La universidad permite cursar hasta tres materias por cuatrimestre. Cada materia consta de dos evaluaciones parciales, la posibilidad de promoci\u00f3n o, caso contrario, de rendir un ex\u00e1men final para su aprobaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 es UBA XXI?<\/strong><\/p>\n<p>UBA XXI es el Programa de Educaci\u00f3n a Distancia de la Universidad de Buenos Aires. El mismo se cre\u00f3 por Resoluci\u00f3n No 1264\/85 del Rector Normalizador.<\/p>\n<p>La iniciativa fue pionera en la introducci\u00f3n de la modalidad a distancia en la educaci\u00f3n superior en la Argentina. La organizaci\u00f3n, coordinaci\u00f3n y supervisi\u00f3n de su funcionamiento es competencia y responsabilidad de la Secretar\u00eda de Asuntos Acad\u00e9micos de la Universidad.<\/p>\n<p>De esta manera, los estudiantes tiene la posibilidad de cursar a distancia las materias del Ciclo B\u00e1sico Com\u00fan (CBC) de todas las carreras. Las materias se dictan a trav\u00e9s de un entorno virtual de aprendizaje, al que se accede de manera remota.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Requisitos y documentaci\u00f3n:<\/strong><\/p>\n<p>El ingreso a la UBA es irrestricto y sin examen de ingreso. Los estudios de grado en la UBA son gratuitos.<\/p>\n<p>Para realizar el proceso de inscripci\u00f3n, se necesita tener el DNI argentino vigente. Por otro lado, la persona interesada en inscribirse deber\u00e1 haber finalizado sus estudios secundarios.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Estudios secundarios<\/strong><\/p>\n<p>Se necesita el certificado de estudios medios completos (t\u00edtulo secundario) legalizado por la Direcci\u00f3n de Legalizaciones de la UBA. La legalizaci\u00f3n se realiza a trav\u00e9s de TAD (Tr\u00e1mites a Distancia), seleccionando la opci\u00f3n de &#8220;Solicitud de Legalizaci\u00f3n de t\u00edtulos secundarios y convalidaci\u00f3n de secundarios&#8221;.<\/p>\n<p>Si el t\u00edtulo a\u00fan no ha sido emitido, se debe presentar una constancia de estudios secundarios completos en tr\u00e1mite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las inscripciones para alumnos al Ciclo B\u00e1sico Com\u00fan 2025 y a UBA XXI abrieron hoy y continuar\u00e1n hasta el 29 de noviembre. Esta instancia apunta a todas las personas que inicien una carrera por primera vez &nbsp; &nbsp; La Universidad de Buenos Aires (UBA) abre sus primeras etapas de inscripci\u00f3n de cara al ciclo lectivo de 2025. Desde hoy y hasta el 29 de noviembre estar\u00e1 abierta la inscripci\u00f3n al Ciclo B\u00e1sico Com\u00fan y a UBA XXI para alumnos que nunca se hayan anotado en la universidad. El proceso de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":122951,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/122950"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=122950"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/122950\/revisions"}],"predecessor-version":[{"id":122952,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/122950\/revisions\/122952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/122951"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=122950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=122950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=122950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}