{"id":122921,"date":"2024-11-20T11:37:15","date_gmt":"2024-11-20T14:37:15","guid":{"rendered":"https:\/\/www.actualidadadiario.com\/?p=122921"},"modified":"2024-11-20T11:37:15","modified_gmt":"2024-11-20T14:37:15","slug":"ambientalistas-fueron-al-senado-y-criticaron-el-proyecto-que-regula-los-agroquimicos-las-buenas-practicas-no-existen","status":"publish","type":"post","link":"https:\/\/www.actualidadadiario.com\/index.php\/2024\/11\/20\/ambientalistas-fueron-al-senado-y-criticaron-el-proyecto-que-regula-los-agroquimicos-las-buenas-practicas-no-existen\/","title":{"rendered":"Ambientalistas fueron al Senado y criticaron el proyecto que regula los agroqu\u00edmicos: \u201cLas buenas pr\u00e1cticas no existen\u201d"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>Organizaciones ambientales, profesionales en la materia y vecinos autoconvocados fueron convocados por la Comisi\u00f3n de Salud, la de Ambiente y la de Producci\u00f3n del Senado con el fin de analizar el proyecto de ley que regula el uso de agroqu\u00edmicos. Afirmaron que el proyecto \u201cadolece de fundamentaciones cient\u00edficas\u201d, \u201cpeca de inconstitucional\u201d y que \u201clas buenas pr\u00e1cticas no existen\u201d. Tambi\u00e9n pusieron el foco en las distancias: \u201cSon alejadas de lo que la Justicia y la ciencia sugieren\u201d<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Este martes tuvo lugar una nueva reuni\u00f3n conjunta de las Comisiones de Salud P\u00fablica y Drogadicci\u00f3n, Ambiente y Desarrollo Sustentable, y de Producci\u00f3n para continuar con el an\u00e1lisis del \u201cProyecto de Ley de buenas pr\u00e1cticas en la utilizaci\u00f3n de fitosanitarios y domisanitarios en la provincia de Entre R\u00edos\u201d.<\/p>\n<p>El encuentro de trabajo tuvo una duraci\u00f3n de cinco horas y se desarroll\u00f3 en el recinto de la C\u00e1mara de Senadores, con algunos invitados de manera presencial y varios con la modalidad videoconferencia.<\/p>\n<p>Encabezaron la reuni\u00f3n quien preside la comisi\u00f3n Salud P\u00fablica y Drogadicci\u00f3n, Hern\u00e1n M\u00e9ndez (Ibicuy \u2013 Juntos por Entre R\u00edos), la titular de la Comisi\u00f3n de Ambiente y Desarrollo Sustentable, Gloria Cozzi (Concordia \u2013 Juntos por Entre R\u00edos) y el presidente de Producci\u00f3n, Casiano Otaegui (Gualeguay \u2013 Juntos por Entre R\u00edos).<\/p>\n<p>Los ambientalistas enviaron d\u00edas atr\u00e1s una nota a las autoridades de comisi\u00f3n (nota que cont\u00f3 con la adhesi\u00f3n de m\u00e1s de 500 firmas) solicitando que un listado de 22 especialistas tenga la posibilidad de expresar su postura ante los senadores.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>De ellos tomaron la palabra los siguientes especialistas y vecinos:<\/strong><\/p>\n<p>-El doctor en Ciencias Naturales, investigador del Conicet, profesor de Eco toxicolog\u00eda de la Universidad Nacional del Litoral, Rafael Lajmanovich.<\/p>\n<p>-La abogada, Magister en Derecho Ambiental, Derecho Urban\u00edstico y Tutela del Patrimonio Cultural, Mar\u00eda Aldana Sasia.<\/p>\n<p>-El m\u00e9dico y docente de la Universidad Nacional de Rosario, Dami\u00e1n Verze\u00f1assi-<\/p>\n<p>-La periodista ambiental e investigadora Anabel Pomar.<\/p>\n<p>-Nicol\u00e1s Indel\u00e1ngelo, ingeniero agr\u00edcola agroecol\u00f3gico.<\/p>\n<p>-Nadia Burgos. Ecosocialista Roja<\/p>\n<p>-Ximena Rosso, representantes de vecinos autoconvocados de Colonia Ensayo<\/p>\n<p>-Cynthia Arellano, representante de vecinos autoconvocados de Colonia Ensayo.<\/p>\n<p>-Facundo Scattone Moulins, Brote Ecol\u00f3gico de Concordia.<\/p>\n<p>-Mar\u00eda Cristina Tejedor, miembro de la Ronda de los Martes de Concepci\u00f3n del Uruguay y Encuentro Ambiental Uruguayense.<\/p>\n<p>-Emilio Vitale, Cordinadora Basta es Basta de Gualeguaych\u00fa.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201cLa casta del campo\u201d<\/strong><\/p>\n<p>En representaci\u00f3n del MST en el FIT- Unidad y la Red Ecosocialista estuvo presente la dirigente Nadia Burgos<\/p>\n<p>Se\u00f1al\u00f3 que el rechazo al proyecto \u201cno es un caprichoso, sino que es producto de a\u00f1os de lucha contra un modelo agotado y cuyas consecuencias sufrimos el 99% de la poblaci\u00f3n y los territorios que habitamos\u201d.<\/p>\n<p>Luego puso sobre la mesa una serie de datos de los pueblos fumigados: \u201cUna es la curva de crecimiento del uso de agrot\u00f3xicos en nuestro pa\u00eds, que desde 1990 aument\u00f3 un 1400 %\u201d.<\/p>\n<p>\u201cCon la soja como una de las producciones de mayor salto en estos a\u00f1os y que hoy ocupa el 60% de la tierra cultivada del pa\u00eds, este modelo empuja el desmonte volvi\u00e9ndonos uno de los 10 pa\u00edses con m\u00e1s deforestaci\u00f3n del mundo\u201d, advirti\u00f3 Burgos.<\/p>\n<p>\u201cLos resultados de un modelo productivo que dec\u00edan iba alimentar el mundo muestran que el 25% de la poblaci\u00f3n sufre inseguridad alimentaria o, como sucede en nuestro pa\u00eds, el 50% de la ni\u00f1ez est\u00e1 bajo la l\u00ednea de pobreza\u201d.<\/p>\n<p>Luego asever\u00f3 que \u201cesta ley legaliza un modelo productivo que tiene como una de las principales consecuencias en nuestra provincia la concentraci\u00f3n de tierras. Hay 190 firmas que controlan m\u00e1s del 25% de la tierra cultivada. Son 524.775 hect\u00e1reas que representan el 42% de tierra trabajada por nuevos actores, megaempresas no entrerrianas, pooles locales y grandes propietarios que tambi\u00e9n generan una concentraci\u00f3n productiva, desplazando del campo a familias enteras mediante la concentraci\u00f3n y monopolio de la tecnolog\u00eda y fuerza productiva\u201d.<\/p>\n<p>\u201cEste modelo productivo bajo el imperativo de la ganancia que disloca la producci\u00f3n de las necesidades sociales no va m\u00e1s. En t\u00e9rminos econ\u00f3micos es necesario reconocer que no existe producci\u00f3n que d\u00e9 ganancias en el agronegocio sin fuertes est\u00edmulos econ\u00f3micos por parte de los gobiernos. La casta del campo, que son los planeros vip de los que nadie quiere hablar, a quienes le declaran la emergencia por sequ\u00eda, por inundaciones, a quienes le bajan los aranceles de los agrot\u00f3xicos, etc. Y esto es as\u00ed porque el paquete tecnol\u00f3gico es cada vez m\u00e1s caro, en d\u00f3lares, y porque la din\u00e1mica de producci\u00f3n de commodities est\u00e1 atada a una demanda no natural, la del mercado, que todos sabemos no se regula solo\u201d.<\/p>\n<p>\u201cLa crisis capitalista actual no es solo econ\u00f3mica, es sist\u00e9mica y est\u00e1 impulsada por factores propios de este sistema en decadencia, no hay rindes en el campo porque bajo el consumo, porque las consecuencias ambientales ya est\u00e1n presentes, los suelos se agotan, las lluvias. son escasas, las ganancias no son las que esperan y as\u00ed se multiplican proyectos como el RIGI y el RINI con exenciones impositivas, aduaneras, o pedidos como el de los productores de megagranjas porcinas que pegan el grito. en el cielo pidiendo subsidios a la luz, a su producci\u00f3n para que la &#8216;competencia sea leal&#8217; frente a otras producci\u00f3n altamente subsidiadas\u201d, agreg\u00f3 el dirigente de izquierda.<\/p>\n<p>\u201cEstos proyectos de ley avalan ese modelo y adem\u00e1s lo hacen apelando a garantizar la calidad e inocuidad de los productos derivados de la actividad productiva, de proteger y conservar la salud, de gozar de un ambiente sano y equilibrado y de favorecer una producci\u00f3n agr\u00edcola que Contribuya a la seguridad alimentaria y al desarrollo rural sostenible. Son C\u00cdNICOS: \u00bfno inocuidad en la utilizaci\u00f3n de productos t\u00f3xicos?, no hay equilibrio en la utilizaci\u00f3n de venenos, no pueden declarar de inter\u00e9s p\u00fablico la legalizaci\u00f3n estatal de este modelo productivo\u201d.<\/p>\n<p>\u201cNo queremos m\u00e1s enga\u00f1os, porque sabemos que esta ley no es nueva, ni aggiornada, ni moderna. Es un intento fallido que insiste, ya frenamos en el 2014 el mamarracho de Arletaz y Cresto, nos manifestamos en una audiencia p\u00fablica e hicimos caer en el 2017 el texto bochornoso de Giano y Torres. Y tambi\u00e9n cuando ingres\u00f3 a la c\u00e1mara de diputados en 2022 esta ley de Bordet la rechazamos. Nos toca una vez m\u00e1s expresar desde la lucha un rechazo, un rechazo que abre un poquito m\u00e1s el camino para que una transici\u00f3n a otro modelo productivo sea posible, porque con estas instancias cada vez m\u00e1s personas se entran que lo nuestro no es el fundamentalismo del NO. Que el fundamentalismo del NO lo tiene el agronegocio de las corporaciones, que hace lobby para que esta ley se concrete e imposibilitar otras formas de producci\u00f3n. Nosotros luchamos por un modelo productivo de y para las poblaciones, donde se decide democr\u00e1ticamente qu\u00e9 y c\u00f3mo se produce. Que se produce al servicio de las mayor\u00edas sociales y el ambiente\u201d.<\/p>\n<p>\u201cPara terminar queremos expresar una vez m\u00e1s que las \u00fanicas buenas pr\u00e1cticas son agr\u00edcolas sin venenos y es con agricultura con agricultores\u201d, finaliz\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201cHallaron glifosato en la orina de las personas\u201d<\/strong><\/p>\n<p>Otro de los que tom\u00f3 la palabra fue el doctor en Ciencias Naturales, investigador del Conicet, profesor de Eco toxicolog\u00eda de la Universidad Nacional del Litoral, Rafael Lajmanovich.<\/p>\n<p>El especialista en impactos de agroqu\u00edmicos se explay\u00f3 sobre diferentes investigaciones a lo largo de las \u00faltimas d\u00e9cadas. Se\u00f1al\u00f3 que a partir del 2008\/2010 empezaron a aparecer m\u00e1s residuos de glifosato en muchas matrices, y en 2016 un estudio sobre el r\u00edo Paran\u00e1 confirm\u00f3 residuos en los sedimentos, principalmente de herbicidas, insecticidas y fungicidas con concentraciones de alto riesgo.<\/p>\n<p>Lajmanovich confirm\u00f3 que Argentina marca r\u00e9cord en residuos de este tipo, y en un estudio reciente se encontraron concentraciones de glifosato en tejidos y m\u00fasculos de s\u00e1balos. En distintas partes del pa\u00eds se encuentran resultados similares en agua, sedimentos y hasta en la lluvia, y existen investigaciones que hallaron glifosato en la orina de personas, por lo que \u201cla problem\u00e1tica es cada vez mayor\u201d.<\/p>\n<p>El experto apunt\u00f3 al movimiento de los plaguicidas en el ambiente lo que es un tema muy complejo y que la cercan\u00eda a los lugares de aplicaci\u00f3n aumenta el riesgo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201cLas buenas pr\u00e1cticas no existen\u201d<\/strong><\/p>\n<p>Luego fue el turno de la abogada, Magister en Derecho Ambiental, Derecho Urban\u00edstico y Tutela del Patrimonio Cultural, Mar\u00eda Aldana Sasia. En su experiencia de llevar adelante varios casos judiciales por da\u00f1os a poblaciones y medio ambiente, el profesional se centr\u00f3 en los fundamentos de los fallos. \u201cHablamos de la salud de todos los entrerrianos\u201d, manifest\u00f3, para afirmar que los impactos de los fitosanitarios persisten por tres generaciones.<\/p>\n<p>\u201cEste proyecto peca de inconstitucional\u201d asever\u00f3, tras lo cual enumera que no se adec\u00faa al estado de la ciencia actual, al principio de no regresi\u00f3n, de objetivaci\u00f3n de la tutela ambiental, entre otros puntos. Sasia cuestion\u00f3 el tema de las cortas distancias para fumigar y la aseveraci\u00f3n de que los productos son inocuos.<\/p>\n<p>\u201cLas buenas pr\u00e1cticas no existen, por distintas variables el producto llega a un lugar distinto de donde se tir\u00f3\u201d, por lo que \u201clos controles son imposibles, hay pruebas contundentes en fallos judiciales\u201d agreg\u00f3.<\/p>\n<p>M\u00e1s hizo adelante destac\u00f3 en los 2.334 principios activos y 6.480 productos formulados aprobados por Senasa, organismo que apunta a lo agudo de la toxicidad y no a lo cr\u00f3nico de los efectos, en tanto en la provincia de Entre R\u00edos no hay registros de casos cr\u00f3nicos. Para finalizar entendi\u00f3 que \u201ces necesario regular las distancias de aplicaci\u00f3n, ampliarlas y rever el modelo de producci\u00f3n\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201cEl proyecto adolescente de fundamentaciones cient\u00edficas\u201d<\/strong><\/p>\n<p>Luego y por videoconferencia hizo su exposici\u00f3n el m\u00e9dico y docente de la Universidad Nacional de Rosario, Dami\u00e1n Verze\u00f1assi. \u201cHace m\u00e1s de 20 a\u00f1os trabajo en los impactos de los modelos de producci\u00f3n\u201d comenz\u00f3 diciendo ante los legisladores.<\/p>\n<p>Asever\u00f3 que los productos fitosanitarios producen intoxicaci\u00f3n aguda y toxicidad cr\u00f3nica. Entre estos \u00faltimos ubic\u00f3 al c\u00e1ncer, que se ha demostrado que distintos tipos de la enfermedad tienen relaci\u00f3n con la exposici\u00f3n, y tanto en Entre R\u00edos la exposici\u00f3n es intensiva. El profesional ahond\u00f3 en estudios que demuestran los da\u00f1os en la salud de la poblaci\u00f3n.<\/p>\n<p>Entendi\u00f3 que el proyecto de ley que est\u00e1 en an\u00e1lisis \u201cadolece de fundamentaciones cient\u00edficas\u201d. Seguidamente se pregunt\u00f3 por las distancias contempladas en el texto, para decir que deben tenerse en cuenta los 1095 metros fijados por la Justicia.<\/p>\n<p>Verze\u00f1assi cit\u00f3 varios ejemplos de productos de banda verde (tambi\u00e9n conocidos como clase IV, se consideran productos con menor toxicidad) los cuales no son inocuos y acarrear\u00edan m\u00faltiples consecuencias, y puso de aliviar que hay conflictos de intereses que hay que tener en claro.<\/p>\n<p>Por \u00faltimo, pidi\u00f3 una ley en funci\u00f3n de la salud y la vida de la poblaci\u00f3n.<\/p>\n<p>Las distancias est\u00e1n alejadas de lo que marca la ciencia.<\/p>\n<p>Tambi\u00e9n por pantalla se hizo presente a la periodista ambiental e investigadora Anabel Pomar. \u201cLas propias empresas que fabrican los productos ocultan la peligrosidad de los mismos\u201d asever\u00f3.<\/p>\n<p>En contra del proyecto de ley, se\u00f1al\u00f3 que no garantiza la salud de la poblaci\u00f3n y las distancias de aplicaci\u00f3n contempladas son alejadas de lo que la Justicia y la ciencia sugieren. \u201cLos fabricantes pagan para mentir y seguir comercializando productos y ocultan los da\u00f1os\u201d, manifest\u00f3, y denunci\u00f3 que en Argentina se aplican fitosanitarios prohibidos de m\u00e1s de 40 pa\u00edses del mundo y no se monitorean.<\/p>\n<p>Pomar tambi\u00e9n cuestion\u00f3 la base cient\u00edfica del proyecto de ley y finaliz\u00f3 sosteniendo que la vida de las personas no tiene precio.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>El proyecto \u201ctiene fuerte arraigo en lo comercial\u201d<\/strong><\/p>\n<p>Por su parte, Nicol\u00e1s Indel\u00e1ngelo, ingeniero agr\u00edcola, se pregunt\u00f3 d\u00f3nde est\u00e1 el m\u00e9todo cient\u00edfico en el proyecto de ley. \u201cEntiendo que se busca validar el uso por ejemplo de drones, pero sin evidencia cient\u00edfica; los jueces fallan sobre la evidencia y se arroj\u00f3 una aplicaci\u00f3n a 1000 metros de distancia\u201d por lo que \u201creclamamos la evidencia cient\u00edfica en el Poder Legislativo\u201d.<\/p>\n<p>El profesional cit\u00f3 que en la localidad de Oro Verde se ha encontrado en el aire, en el agua y en el suelo la presencia de M\u00faltiples agroqu\u00edmicos, tras lo cual se\u00f1al\u00f3 que \u201cno se maneja la din\u00e1mica ambiental y es alto el porcentaje de producto que llega a cualquier lugar\u201d. Indel\u00e1ngelo dijo a los senadores que \u201cestamos alarmados porque estamos condenados por la gran cantidad de aplicaciones por hect\u00e1rea y cada vez se usan m\u00e1s agroqu\u00edmicos, la tendencia es creciente y exponencial, son un negocio fant\u00e1stico para multinacionales\u201d.<\/p>\n<p>El ingeniero opin\u00f3 que \u201ceste articulado tiene fuerte arraigo en lo comercial y tenemos que pensar en los habitantes de este suelo, poner la agenda en la disminuci\u00f3n del uso de agroqu\u00edmicos\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La voz de los vecinos<\/strong><\/p>\n<p>En representaci\u00f3n de vecinos autoconvocados de Colonia Ensayo, Ximena Rosso y Cynthia Arellano rechazaron el proyecto de ley. \u201cEn Colonia Ensayo hay 18 barrios nuevos porque los productores lotearon los campos\u201d y se\u00f1al\u00f3 que \u201csoy una vecina fumigada y no queremos que nos envenenen\u201d.<\/p>\n<p>\u201cHay un Estado ausente y se habla de m\u00e1s veneno a menos distancia\u201d. Por su parte Rosso indic\u00f3 que \u201cfuimos beneficiadas por el amparo y pedimos mayores distancias en las fumigaciones\u201d.<\/p>\n<p>En el mismo sentido, Facundo Scattone Moulins desde Concordia por videoconferencia, manifest\u00f3 el rechazo al proyecto y al modelo de producci\u00f3n y pidi\u00f3 avanzar en un proyecto con base s\u00f3lida en la salud.<\/p>\n<p>El ambientalista hizo hincapi\u00e9 en que no hay consenso sobre el proyecto de ley, el que fue hecho a su entender por la Mesa de Buenas Pr\u00e1cticas Agr\u00edcolas.<\/p>\n<p>Desde Concepci\u00f3n del Uruguay, tambi\u00e9n por pantalla, Mar\u00eda Cristina Tejedor miembro de la Ronda de los Martes y Encuentro Ambiental Uruguayense, habl\u00f3 de lobby en el proyecto de ley.<\/p>\n<p>Se\u00f1al\u00f3 que el texto \u201ces como una trampa para institucionalizar a las Buenas Pr\u00e1cticas Agropecuarias (BPA)\u201d.<\/p>\n<p>Como muchos de los expositores que la precedieron en la palabra, tambi\u00e9n cuestionaron las cortas distancias contempladas en las aplicaciones.<\/p>\n<p>Por \u00faltimo, desde Gualeguaych\u00fa, Emilio Vitale, referente de una organizaci\u00f3n ambientalista, entendi\u00f3 que el proyecto de ley \u201cno contempla controles ambientales ni durante ni despu\u00e9s de las aplicaciones\u201d por lo que no se puede certificar la buena pr\u00e1ctica agropecuaria.<\/p>\n<p>Por videoconferencia abog\u00f3 por informar los expedientes en materia ambiental, utilizar mayor tecnolog\u00eda para evaluar impactos, e impulsar el menor uso de los productos fitosanitarios apuntando a los beneficios de la agroecolog\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organizaciones ambientales, profesionales en la materia y vecinos autoconvocados fueron convocados por la Comisi\u00f3n de Salud, la de Ambiente y la de Producci\u00f3n del Senado con el fin de analizar el proyecto de ley que regula el uso de agroqu\u00edmicos. Afirmaron que el proyecto \u201cadolece de fundamentaciones cient\u00edficas\u201d, \u201cpeca de inconstitucional\u201d y que \u201clas buenas pr\u00e1cticas no existen\u201d. Tambi\u00e9n pusieron el foco en las distancias: \u201cSon alejadas de lo que la Justicia y la ciencia sugieren\u201d &nbsp; &nbsp; Este martes tuvo lugar una nueva reuni\u00f3n conjunta de las Comisiones de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":46039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/122921"}],"collection":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/comments?post=122921"}],"version-history":[{"count":1,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/122921\/revisions"}],"predecessor-version":[{"id":122922,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/posts\/122921\/revisions\/122922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media\/46039"}],"wp:attachment":[{"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/media?parent=122921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/categories?post=122921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.actualidadadiario.com\/index.php\/wp-json\/wp\/v2\/tags?post=122921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}